{"id":1032,"date":"2020-09-22T09:57:55","date_gmt":"2020-09-22T12:57:55","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1032"},"modified":"2020-09-22T09:57:59","modified_gmt":"2020-09-22T12:57:59","slug":"suspeito-de-mandar-matar-pai-e-filho-se-entrega-a-policia","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/09\/22\/suspeito-de-mandar-matar-pai-e-filho-se-entrega-a-policia\/","title":{"rendered":"Suspeito de mandar matar pai e filho se entrega \u00e0 pol\u00edcia"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Secretaria de Seguran\u00e7a P\u00fablica (SSP) de Sergipe informou nesta ter\u00e7a-feira (22) que o homem suspeito de mandar matar\u00a0pai e filho no munic\u00edpio de Nossa Senhora das Dores\u00a0se apresentou \u00e0 pol\u00edcia no dia 17 de setembro. O crime ocorreu no dia 4 de julho, quando homens encapuzados chegaram em um carro e atiraram contra v\u00edtimas, que tinham 52 e 29 anos, e estavam trabalhando como pedreiros na obra de uma casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com as investiga\u00e7\u00f5es, o suspeito teria pago R$ 8 mil aos executores do crime. Ele tamb\u00e9m \u00e9 apontado como o principal suspeito de um homic\u00eddio cometido em 2019, no Povoado Tabocas, localizado na mesma cidade, que vitimou um homem que era filho e irm\u00e3o das v\u00edtimas de julho deste ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A motiva\u00e7\u00e3o para o crime teria tido in\u00edcio com um desentendimento ocorrido no ano passado, por um suposto acidente de tr\u00e2nsito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">As investiga\u00e7\u00f5es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A SSP informou que foram analisadas as imagens das c\u00e2meras de seguran\u00e7a da prefeitura da cidade e de populares da localidade e foi poss\u00edvel identificar o ve\u00edculo utilizado na a\u00e7\u00e3o criminosa. O dono do carro foi ouvido, entrou em contradi\u00e7\u00e3o e foi preso preventivamente no dia 18 de agosto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na segunda fase do procedimento investigativo, com dilig\u00eancias em Alagoas, um dos suspeito de atirar contras as v\u00edtimas foi preso e confessou o crime. Ele apontou a participa\u00e7\u00e3o de outros dois homens. Um deles tamb\u00e9m teria efetuado os disparos e o outro ficou no carro com um quarto suspeito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As buscas seguem para chegar \u00e0s localiza\u00e7\u00f5es de Welson Jesu\u00edno dos Santos e de C\u00edcero Gomes da Silva. Informa\u00e7\u00f5es e den\u00fancias podem ser repassadas pelo Disque-Den\u00fancia (181).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte G1 Se<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Seguran\u00e7a P\u00fablica (SSP) de Sergipe informou nesta ter\u00e7a-feira (22) que o homem suspeito de mandar matar\u00a0pai e filho no munic\u00edpio de Nossa Senhora das Dores\u00a0se apresentou \u00e0 pol\u00edcia no dia 17 de setembro. O crime ocorreu no dia 4 de julho, quando homens encapuzados chegaram em um carro e atiraram contra v\u00edtimas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,33],"tags":[],"class_list":["post-1032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-policial"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-22-at-09.54.06.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1032"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1032\/revisions"}],"predecessor-version":[{"id":1034,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1032\/revisions\/1034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1033"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}