{"id":1035,"date":"2020-09-22T11:41:52","date_gmt":"2020-09-22T14:41:52","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1035"},"modified":"2020-09-22T11:41:56","modified_gmt":"2020-09-22T14:41:56","slug":"idoso-morre-e-outras-duas-pessoas-ficam-feridas-apos-serem-atingidas-por-carro-desgovernado-em-estancia","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/09\/22\/idoso-morre-e-outras-duas-pessoas-ficam-feridas-apos-serem-atingidas-por-carro-desgovernado-em-estancia\/","title":{"rendered":"Idoso morre e outras duas pessoas ficam feridas ap\u00f3s serem atingidas por carro desgovernado em Est\u00e2ncia"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um idoso de 78 anos morreu ap\u00f3s ser atropelado no munic\u00edpio de Est\u00e2ncia, regi\u00e3o sul de Sergipe. O acidente aconteceu na avenida&nbsp;Raimundo Silveira Souza, no&nbsp;bairro Alagoas, por volta das 9h30 desta ter\u00e7a-feira (22), quando o motorista de um ve\u00edculo passou mal e perdeu o controle da dire\u00e7\u00e3o do carro, e saiu atingindo o que estava na frente, o carro atropelou o idoso, que morreu no local e outra pessoa que foi encaminhada ao hospital.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ve\u00edculo s\u00f3 parou ao atingir o muro de uma autoescola e um poste, que acabou caindo, com o forte impacto.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte Asse<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um idoso de 78 anos morreu ap\u00f3s ser atropelado no munic\u00edpio de Est\u00e2ncia, regi\u00e3o sul de Sergipe. O acidente aconteceu na avenida&nbsp;Raimundo Silveira Souza, no&nbsp;bairro Alagoas, por volta das 9h30 desta ter\u00e7a-feira (22), quando o motorista de um ve\u00edculo passou mal e perdeu o controle da dire\u00e7\u00e3o do carro, e saiu atingindo o que estava [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1036,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[38,2],"tags":[],"class_list":["post-1035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acidente","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/09\/3014669541-acidente-estancia.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1035"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1035\/revisions"}],"predecessor-version":[{"id":1037,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1035\/revisions\/1037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1036"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}