{"id":1092,"date":"2020-09-25T08:47:19","date_gmt":"2020-09-25T11:47:19","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1092"},"modified":"2020-09-25T08:47:20","modified_gmt":"2020-09-25T11:47:20","slug":"homem-e-preso-em-flagrante-suspeito-de-trafico-de-drogas-em-boquim","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/09\/25\/homem-e-preso-em-flagrante-suspeito-de-trafico-de-drogas-em-boquim\/","title":{"rendered":"Homem \u00e9 preso em flagrante suspeito de tr\u00e1fico de drogas em Boquim"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Policiais da 2\u00aa Companhia do 6\u00ba Batalh\u00e3o de Pol\u00edcia Militar (2\u00aa Cia \/ 6\u00ba BPM) prenderam um homem de 24 anos suspeito pelo crime de tr\u00e1fico de drogas. A deten\u00e7\u00e3o em flagrante ocorreu nesta quinta-feira, 24, na cidade de Boquim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com as informa\u00e7\u00f5es policiais, ap\u00f3s den\u00fancias, os militares intensificaram as rondas e chegaram ao suspeito. Na abordagem, foram localizados material para embalagem de entorpecente, mat\u00e9ria-prima para o preparo de drogas e dinheiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante do flagrante, o suspeito e o material apreendido foram encaminhados \u00e0 delegacia, para ado\u00e7\u00e3o das demais medidas legais cab\u00edveis ao caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte Infonet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Policiais da 2\u00aa Companhia do 6\u00ba Batalh\u00e3o de Pol\u00edcia Militar (2\u00aa Cia \/ 6\u00ba BPM) prenderam um homem de 24 anos suspeito pelo crime de tr\u00e1fico de drogas. A deten\u00e7\u00e3o em flagrante ocorreu nesta quinta-feira, 24, na cidade de Boquim. De acordo com as informa\u00e7\u00f5es policiais, ap\u00f3s den\u00fancias, os militares intensificaram as rondas e chegaram [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1093,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,33],"tags":[],"class_list":["post-1092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-policial"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/09\/policia-militar-flagrante-boquim-25092020-ssp.jpg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1092"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1092\/revisions"}],"predecessor-version":[{"id":1094,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1092\/revisions\/1094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1093"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}