{"id":1203,"date":"2020-10-07T17:56:48","date_gmt":"2020-10-07T20:56:48","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1203"},"modified":"2020-10-07T17:56:52","modified_gmt":"2020-10-07T20:56:52","slug":"motociclista-morre-apos-colisao-com-veiculo-na-rodovia-se-270","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/10\/07\/motociclista-morre-apos-colisao-com-veiculo-na-rodovia-se-270\/","title":{"rendered":"Motociclista morre ap\u00f3s colis\u00e3o com ve\u00edculo na rodovia SE-270"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um motociclista morreu ap\u00f3s se envolver em acidente com um ve\u00edculo de passeio durante a manh\u00e3 desta quarta-feira, 7, por volta das 11 horas, na Rodovia Lourival Baptista (SE-270), em trecho que fica pr\u00f3ximo ao povoado Rio Fundo, no munic\u00edpio de Itaporanga D\u2019ajuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria Estadual (BPRv), o carro e a moto trafegavam em dire\u00e7\u00f5es opostas na rodovia quando houve a colis\u00e3o frontal entre os ve\u00edculos que resultou na morte do motociclista. O condutor do carro realizou o teste do baf\u00f4metro e n\u00e3o apresentou sinal de embriaguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU) foi acionado por policiais que estavam presentes no local do acidente, mas a v\u00edtima n\u00e3o resistiu aos ferimentos e foi a \u00f3bito. Segundo o batalh\u00e3o, equipes do Instituto M\u00e9dico Legal e da Criminal\u00edstica foram acionadas e os ve\u00edculos foram encaminhados \u00e0 Delegacia de Itaporanga D\u2019ajuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um motociclista morreu ap\u00f3s se envolver em acidente com um ve\u00edculo de passeio durante a manh\u00e3 desta quarta-feira, 7, por volta das 11 horas, na Rodovia Lourival Baptista (SE-270), em trecho que fica pr\u00f3ximo ao povoado Rio Fundo, no munic\u00edpio de Itaporanga D\u2019ajuda. De acordo com o Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria Estadual (BPRv), o carro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[38,2],"tags":[],"class_list":["post-1203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acidente","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/10\/acidente-de-moto-na-rodovia-270-foto-BPRv.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1203"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1203\/revisions"}],"predecessor-version":[{"id":1205,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1203\/revisions\/1205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1204"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}