{"id":1253,"date":"2020-10-13T08:17:54","date_gmt":"2020-10-13T11:17:54","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1253"},"modified":"2020-10-13T08:18:00","modified_gmt":"2020-10-13T11:18:00","slug":"cptran-autua-22-condutores-embriagados-durante-a-operacao-padroeira","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/10\/13\/cptran-autua-22-condutores-embriagados-durante-a-operacao-padroeira\/","title":{"rendered":"CPTran autua 22 condutores embriagados durante a Opera\u00e7\u00e3o Padroeira"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Companhia de Policiamento de Tr\u00e2nsito (CPTran) informou nesta ter\u00e7a-feira (13) que 22 pessoas foram autuadas por embriaguez em Aracaju durante a Opera\u00e7\u00e3o Padroeira, entre os dias 9 e 12 de outubro. O fluxo de ve\u00edculos foi intenso nas sa\u00eddas da capital, principalmente na Avenida Mel\u00edcio Machado e em dire\u00e7\u00e3o ao munic\u00edpio da Barra dos Coqueiros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o per\u00edodo, foram registrados 9 acidentes de tr\u00e2nsito &#8211; dois deles com condutores flagrados pela Lei Seca.Ao todo, sete pessoas ficaram feridas e n\u00e3o houve mortes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a CPTran, a fiscaliza\u00e7\u00e3o evitou a circula\u00e7\u00e3o imprudente de ve\u00edculos na faixa litor\u00e2nea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte G1 Sergipe<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Companhia de Policiamento de Tr\u00e2nsito (CPTran) informou nesta ter\u00e7a-feira (13) que 22 pessoas foram autuadas por embriaguez em Aracaju durante a Opera\u00e7\u00e3o Padroeira, entre os dias 9 e 12 de outubro. O fluxo de ve\u00edculos foi intenso nas sa\u00eddas da capital, principalmente na Avenida Mel\u00edcio Machado e em dire\u00e7\u00e3o ao munic\u00edpio da Barra dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,33],"tags":[],"class_list":["post-1253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-policial"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/10\/cptran.jpg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1253"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1253\/revisions"}],"predecessor-version":[{"id":1255,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1253\/revisions\/1255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1254"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}