{"id":1265,"date":"2020-10-14T09:56:33","date_gmt":"2020-10-14T12:56:33","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1265"},"modified":"2020-10-14T09:56:37","modified_gmt":"2020-10-14T12:56:37","slug":"com-gratificacoes-suspensas-servidores-da-saude-de-se-ameacam-paralisacao","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/10\/14\/com-gratificacoes-suspensas-servidores-da-saude-de-se-ameacam-paralisacao\/","title":{"rendered":"Com gratifica\u00e7\u00f5es suspensas,  servidores da Sa\u00fade de SE amea\u00e7am paralisa\u00e7\u00e3o"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Insatisfeitos com a suspens\u00e3o das\u00a0Gratifica\u00e7\u00f5es por Criticidade e Desempenhos e Resultados, cerca de 2.600\u00a0servidores da Funda\u00e7\u00e3o Hospitalar da Sa\u00fade podem paralisar as atividades. O benef\u00edcio pago desde 2012 foi suspenso no m\u00eas de setembro deste ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o presidente do Sindicato dos Trabalhadores na \u00c1rea da Sa\u00fade do Estado de Sergipe (Sintasa), Augusto Couto, existe um projeto de lei que ir\u00e1 devolver a gratifica\u00e7\u00e3o aos profissionais e o Sindicato est\u00e1 esperando novidades sobre o novo benef\u00edcio. \u201cSe at\u00e9 o dia 15, o Governo n\u00e3o enviar o projeto de lei, a gente j\u00e1 vai ter ficado um m\u00eas sem a gratifica\u00e7\u00e3o\u201d, lamenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Augusto explica que n\u00e3o existiu um aviso pr\u00e9vio sobre a suspens\u00e3o do pagamento e isso deixou os profissionais abalados. \u201cEstamos vivendo num tempo de pandemia e precisamos enxergar o quanto os profissionais da sa\u00fade est\u00e3o ajudando o estado\u201d, comenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a instabilidade gerada, o presidente fala sobre uma poss\u00edvel paralisa\u00e7\u00e3o. \u201cCaso o dia 30 de outubro chegue e o pagamento do benef\u00edcio n\u00e3o tenha sido feito, ser\u00e1 analisada uma poss\u00edvel paralisa\u00e7\u00e3o dos servidores\u201d, comenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A gratifica\u00e7\u00e3o tinha o valor vari\u00e1vel de R$ 100 at\u00e9 6.000 e era paga a m\u00e9dicos, enfermeiros e outros profissionais da \u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Secretaria de Estado da Sa\u00fade (SES) informou atrav\u00e9s de nota, que a suspens\u00e3o das gratifica\u00e7\u00f5es foi uma determina\u00e7\u00e3o do Tribunal de Contas do Estado, mas que devido \u00e0 perda salarial dos funcion\u00e1rios, a secretaria minutou um projeto de lei criando uma nova gratifica\u00e7\u00e3o que contempla as duas. A SES explicou tamb\u00e9m que o projeto de lei j\u00e1 se encontra formatado e aguarda an\u00e1lise do impacto financeiro para ser encaminhado \u00e0 Assembleia Legislativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Insatisfeitos com a suspens\u00e3o das\u00a0Gratifica\u00e7\u00f5es por Criticidade e Desempenhos e Resultados, cerca de 2.600\u00a0servidores da Funda\u00e7\u00e3o Hospitalar da Sa\u00fade podem paralisar as atividades. O benef\u00edcio pago desde 2012 foi suspenso no m\u00eas de setembro deste ano. Segundo o presidente do Sindicato dos Trabalhadores na \u00c1rea da Sa\u00fade do Estado de Sergipe (Sintasa), Augusto Couto, existe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,39],"tags":[],"class_list":["post-1265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-saude"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/10\/unnamed.jpg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1265"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1265\/revisions"}],"predecessor-version":[{"id":1267,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1265\/revisions\/1267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1266"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}