{"id":1281,"date":"2020-10-15T08:51:19","date_gmt":"2020-10-15T11:51:19","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1281"},"modified":"2020-10-15T08:51:23","modified_gmt":"2020-10-15T11:51:23","slug":"setor-de-servicos-sofre-queda-no-mes-de-agosto-em-sergipe","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/10\/15\/setor-de-servicos-sofre-queda-no-mes-de-agosto-em-sergipe\/","title":{"rendered":"Setor de servi\u00e7os sofre queda no m\u00eas de agosto, em Sergipe"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">O Instituto Brasileiro de Geografia e Estat\u00edsticas, o IBGE, divulgou nesta quarta-feira (14) os Indicadores da Pesquisa Mensal de Servi\u00e7os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o estudo, em agosto de 2020 o setor de servi\u00e7os, em Sergipe, mostrou retra\u00e7\u00e3o de 0,3% frente a julho de 2020. Em julho, o volume do setor de servi\u00e7os foi de 2,7%, sendo o primeiro volume positivo do ano de 2020. De acordo com o t\u00e9cnico de informa\u00e7\u00f5es do IBGE, Vinicius Rocha, apesar da retomada econ\u00f4mica no estado j\u00e1 ter iniciado, n\u00e3o houve tanta influ\u00eancia para esses dados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00c9 importante lembrar que esses locais de presta\u00e7\u00e3o de servi\u00e7os tiveram a libera\u00e7\u00e3o s\u00f3 no fim do m\u00eas de agosto, ent\u00e3o esses n\u00fameros n\u00e3o foram t\u00e3o positivos. \u00c9 uma queda pequena, mas \u00e9 uma queda significativa\u201d, revela Vinicius.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao contr\u00e1rio de Sergipe, em \u00e2mbito nacional, o volume de servi\u00e7os avan\u00e7ou 2,9% frente a julho. Foi a terceira taxa positiva seguida no pa\u00eds, acumulando alta de 11,2%, no per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na s\u00e9rie sem ajuste sazonal, em Sergipe, em rela\u00e7\u00e3o a agosto de 2019, o volume de servi\u00e7os recuou 20,8%, seguindo com recuo desde janeiro, por\u00e9m, com quedas mais acentuadas a partir do m\u00eas de mar\u00e7o, por conta da pandemia causada pelo novo coronav\u00edrus. O acumulado de 2020, de janeiro a agosto, teve a maior retra\u00e7\u00e3o registrada do ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo acumulado deste ano, ou seja, quando a gente compara os oito primeiros meses do ano de 2020 com o mesmo per\u00edodo do ano passado, a gente percebe uma queda de 15,3%\u201d, conta Vinicius.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte A8Se<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>O Instituto Brasileiro de Geografia e Estat\u00edsticas, o IBGE, divulgou nesta quarta-feira (14) os Indicadores da Pesquisa Mensal de Servi\u00e7os. Segundo o estudo, em agosto de 2020 o setor de servi\u00e7os, em Sergipe, mostrou retra\u00e7\u00e3o de 0,3% frente a julho de 2020. Em julho, o volume do setor de servi\u00e7os foi de 2,7%, sendo o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[35,2],"tags":[],"class_list":["post-1281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidadania","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/10\/comercio_de_rua_e_saloes_de_bele.2e16d0ba.fill-2220x1000-1.jpg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1281"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1281\/revisions"}],"predecessor-version":[{"id":1283,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1281\/revisions\/1283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1282"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}