{"id":1443,"date":"2020-10-28T14:28:15","date_gmt":"2020-10-28T17:28:15","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1443"},"modified":"2020-10-28T14:28:19","modified_gmt":"2020-10-28T17:28:19","slug":"capotamento-de-micro-onibus-deixa-um-obito-e-varias-pessoas-feridas-em-tobias-barreto","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/10\/28\/capotamento-de-micro-onibus-deixa-um-obito-e-varias-pessoas-feridas-em-tobias-barreto\/","title":{"rendered":"Capotamento de micro-\u00f4nibus deixa um \u00f3bito e v\u00e1rias pessoas feridas em Tobias Barreto"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um micro-\u00f4nibus intermunicipal da Coopertalse perdeu o controle e capotou. O fato aconteceu por volta das 13h30, desta ter\u00e7a-feira (27). Segundo informa\u00e7\u00f5es do Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria Estadual, cerca de onze pessoas estavam no ve\u00edculo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acidente aconteceu entre os munic\u00edpios de Lagarto e Tobias Barreto. Ainda de acordo com o BPRv, das v\u00edtimas, um homem n\u00e3o resistiu e acabou falecendo. Ele tinha 53 anos e era da Bahia. Cinco pessoas foram para a UPA de Tobias Barreto por meios pr\u00f3prios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia, o Samu, informou ainda que dos atendidos, uma mulher de 53 anos, sofreu trauma tor\u00e1cico e abdominal, ela foi removida pelo GTA (Grupamento T\u00e1tico A\u00e9reo) por necessitar de cuidados mais espec\u00edficos. Foi levada ao Huse e est\u00e1 na \u00e1rea vermelha. Outra mulher, com 40 anos, tamb\u00e9m foi levada ao Huse. Um rapaz de 30 anos e uma mulher da mesma idade, foram encaminhados para o Hospital Regional de Lagarto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O caso aconteceu um quil\u00f4metro antes da entrada de Tobias Barreto. O micro-\u00f4nibus foi encaminhado para a delegacia de Tobias Barreto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte A8Se<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um micro-\u00f4nibus intermunicipal da Coopertalse perdeu o controle e capotou. O fato aconteceu por volta das 13h30, desta ter\u00e7a-feira (27). Segundo informa\u00e7\u00f5es do Batalh\u00e3o de Pol\u00edcia Rodovi\u00e1ria Estadual, cerca de onze pessoas estavam no ve\u00edculo. O acidente aconteceu entre os munic\u00edpios de Lagarto e Tobias Barreto. Ainda de acordo com o BPRv, das v\u00edtimas, um [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1444,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[38,2],"tags":[],"class_list":["post-1443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acidente","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/10\/capotamento_c03c9a21469f6110f2ad190c7c90-1.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1443"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1443\/revisions"}],"predecessor-version":[{"id":1445,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1443\/revisions\/1445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1444"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}