{"id":1466,"date":"2020-10-29T16:59:15","date_gmt":"2020-10-29T19:59:15","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1466"},"modified":"2020-10-29T16:59:17","modified_gmt":"2020-10-29T19:59:17","slug":"meia-passagem-para-estudantes-e-retomada-na-capital","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/10\/29\/meia-passagem-para-estudantes-e-retomada-na-capital\/","title":{"rendered":"Meia passagem para estudantes \u00e9 retomada na capital"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Prefeitura de Aracaju revogou nesta quinta-feira, 29, o\u00a0<strong>decreto que restringiu a meia passagem para estudantes que utilizam o transporte p\u00fablico coletivo\u00a0<\/strong>da capital, por meio do cart\u00e3o \u2018Mais Aracaju Escolar\u2019, que d\u00e1 acesso ao desconto de 50% no pagamento da tarifa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A revoga\u00e7\u00e3o do decreto municipal acontece ap\u00f3s a homologa\u00e7\u00e3o, por parte do Governo do Estado, da Resolu\u00e7\u00e3o n\u00ba3 do Comit\u00ea T\u00e9cnico Cient\u00edfico e de Atividades Especiais, que disp\u00f5e sobre a retomada presencial das atividades educacionais em universidades, faculdades, escolas nas esferas p\u00fablicas e privadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O uso do cart\u00e3o estava suspenso desde 24 de mar\u00e7o, em cumprimento ao Decreto Municipal n\u00b0 6.111, que disp\u00f5e sobre as medidas para o enfrentamento emergencial de sa\u00fade p\u00fablica decorrente da infec\u00e7\u00e3o humana pelo novo coronav\u00edrus, estimulando os jovens a se protegerem contra a prolifera\u00e7\u00e3o da covid-19, permanecendo em casa durante o per\u00edodo de suspens\u00e3o das aulas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme a resolu\u00e7\u00e3o estadual, o retorno das aulas ser\u00e1 gradual, progressivo e h\u00edbrido, com limita\u00e7\u00e3o m\u00e1xima de 50% de capacidade da sala de aula, indicando-se, exclusivamente, para alunos do terceiro ano do ensino m\u00e9dio; concludentes da educa\u00e7\u00e3o profissional tecnol\u00f3gica integrada ao Ensino M\u00e9dio; educa\u00e7\u00e3o de jovens e adultos do ensino m\u00e9dio; cursos livres de pr\u00e9-vestibulares e pr\u00e9-Enem; aulas de atividades pr\u00e1ticas de curso de ensino superior; aulas e atividades pr\u00e1ticas de cursos de educa\u00e7\u00e3o profissional tecnol\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A retomada ser\u00e1 a partir de 3 de novembro para a rede particular de ensino e 17 de novembro para a rede p\u00fablica. Contudo, a autoriza\u00e7\u00e3o para a retomada das atividades educacionais, em qualquer caso, fica condicionada \u00e0 publica\u00e7\u00e3o de protocolo espec\u00edfico sanit\u00e1rio, emitido pelas autoridades de sa\u00fade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte Infonet <\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Aracaju revogou nesta quinta-feira, 29, o\u00a0decreto que restringiu a meia passagem para estudantes que utilizam o transporte p\u00fablico coletivo\u00a0da capital, por meio do cart\u00e3o \u2018Mais Aracaju Escolar\u2019, que d\u00e1 acesso ao desconto de 50% no pagamento da tarifa. A revoga\u00e7\u00e3o do decreto municipal acontece ap\u00f3s a homologa\u00e7\u00e3o, por parte do Governo do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[41,2],"tags":[],"class_list":["post-1466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/10\/catraca_onibus_foto_facebook_setransp_11022020.jpg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1466"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1466\/revisions"}],"predecessor-version":[{"id":1468,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1466\/revisions\/1468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1467"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}