{"id":1661,"date":"2020-11-14T10:33:49","date_gmt":"2020-11-14T13:33:49","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=1661"},"modified":"2020-11-14T10:33:56","modified_gmt":"2020-11-14T13:33:56","slug":"justica-autorizou-pesquisa-da-tv-atalaia","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/11\/14\/justica-autorizou-pesquisa-da-tv-atalaia\/","title":{"rendered":"Justi\u00e7a autorizou pesquisa da TV Atalaia"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A pesquisa divulgada na noite de sexta-feira, 13, pela TV Atalaia foi autorizada pela Justi\u00e7a Eleitoral. Registrada com o n\u00famero SE-05674\/2020, a pesquisa aparece no site do TRE\/SE com todas as informa\u00e7\u00f5es aptas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesquisa mostrou a lideran\u00e7a da prefeita Hilda Ribeiro e a consolida\u00e7\u00e3o da reelei\u00e7\u00e3o dela no pr\u00f3ximo domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja os n\u00fameros da pesquisa:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hilda Ribeiro &#8211; 41,44%<br>F\u00e1bio Reis &#8211; 31,52%<br>Ibrain &#8211; 6,74%<br>Nininho da Bolo Bom &#8211; 1,59%<br>Jorge Prata &#8211; 0,09%<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A pesquisa divulgada na noite de sexta-feira, 13, pela TV Atalaia foi autorizada pela Justi\u00e7a Eleitoral. Registrada com o n\u00famero SE-05674\/2020, a pesquisa aparece no site do TRE\/SE com todas as informa\u00e7\u00f5es aptas. A pesquisa mostrou a lideran\u00e7a da prefeita Hilda Ribeiro e a consolida\u00e7\u00e3o da reelei\u00e7\u00e3o dela no pr\u00f3ximo domingo. Veja os n\u00fameros da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-1661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-politica"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-14-at-09.05.29.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1661"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1661\/revisions"}],"predecessor-version":[{"id":1663,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1661\/revisions\/1663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/1662"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}