{"id":2039,"date":"2022-03-11T13:34:15","date_gmt":"2022-03-11T16:34:15","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=2039"},"modified":"2022-03-11T13:34:18","modified_gmt":"2022-03-11T16:34:18","slug":"auxilio-emergencial-indevido-pode-ser-devolvido-em-ate-60-parcelas-veja-regras","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2022\/03\/11\/auxilio-emergencial-indevido-pode-ser-devolvido-em-ate-60-parcelas-veja-regras\/","title":{"rendered":"Aux\u00edlio Emergencial indevido pode ser devolvido em at\u00e9 60 parcelas; veja regras"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Os brasileiros que receberam o&nbsp;Aux\u00edlio Emergencial&nbsp;indevidamente \u2013 tanto em 2020 quanto em 2021\u2013 t\u00eam que devolver o benef\u00edcio \u2013 mas o pagamento poder\u00e1 ser feito em at\u00e9 60 parcelas.&nbsp;<strong>A medida est\u00e1 em um decreto publicado pelo governo nesta quinta-feira (10).<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veja as regras para a devolu\u00e7\u00e3o do dinheiro<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem precisa devolver?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ter\u00e1 que devolver o dinheiro quem recebeu o&nbsp;Aux\u00edlio Emergencial&nbsp;sem ter direito a ele. Isso pode ter acontecido por alguma irregularidade cometida pelo benefici\u00e1rio na hora de fazer o pedido ou erro na concess\u00e3o, ou ainda por erro na manuten\u00e7\u00e3o ou revis\u00e3o \u2013 ou seja, o trabalhador deixou de ter direito ao Aux\u00edlio ao longo do programa, mas continuou recebendo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como saber se eu preciso devolver?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nos casos em que o governo identificar erro, o trabalhador vai ser notificado:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>por meio eletr\u00f4nico (como e-mail),<\/li><li>por mensagem de SMS,<\/li><li>pelo banco,<\/li><li>pelos Correios,<\/li><li>pessoalmente, ou<\/li><li>por edital<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Como devolver?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A devolu\u00e7\u00e3o dever\u00e1 ser feita por meio da emiss\u00e3o de Guia de Recolhimento da Uni\u00e3o (GRU) &#8211; Cobran\u00e7a, que pode ser paga em qualquer banco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O pagamento poder\u00e1 ser feito \u00e0 vista ou em at\u00e9 60 parcelas. Cada parcela, no entanto, n\u00e3o pode ser menor que R$ 50, o valor m\u00ednimo para emiss\u00e3o da GRU.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">E se eu n\u00e3o concordar que houve erro?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O benefici\u00e1rio que discordar da devolu\u00e7\u00e3o, ou ainda do valor a ser devolvido, ter\u00e1 30 dias ap\u00f3s receber a notifica\u00e7\u00e3o para contestar a decis\u00e3o. A defesa deve ser feita pela&nbsp;p\u00e1gina do Minist\u00e9rio da Cidadania na internet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que acontece se eu n\u00e3o devolver?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se o benefici\u00e1rio n\u00e3o devolver o dinheiro voluntariamente, o governo far\u00e1 uma cobran\u00e7a extrajudicial. Se, mesmo ap\u00f3s essa cobran\u00e7a, o valor n\u00e3o for pago, o trabalhador ser\u00e1 inscrito na d\u00edvida ativa da Uni\u00e3o \u2013 e pode ir parar em cadastros de restri\u00e7\u00e3o a cr\u00e9dito, como Serasa, e ser impedido de obter financiamentos e empr\u00e9stimos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem fica isento?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quem recebeu indevidamente, mas teria que devolver menos de R$ 50, fica liberado do pagamento.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Os brasileiros que receberam o&nbsp;Aux\u00edlio Emergencial&nbsp;indevidamente \u2013 tanto em 2020 quanto em 2021\u2013 t\u00eam que devolver o benef\u00edcio \u2013 mas o pagamento poder\u00e1 ser feito em at\u00e9 60 parcelas.&nbsp;A medida est\u00e1 em um decreto publicado pelo governo nesta quinta-feira (10). Veja as regras para a devolu\u00e7\u00e3o do dinheiro Quem precisa devolver? Ter\u00e1 que devolver o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[42],"tags":[],"class_list":["post-2039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2022\/03\/auxilio-emergencial.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2039"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2039\/revisions"}],"predecessor-version":[{"id":2041,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2039\/revisions\/2041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/2040"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}