{"id":2077,"date":"2022-04-16T19:33:14","date_gmt":"2022-04-16T22:33:14","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=2077"},"modified":"2022-04-16T19:33:17","modified_gmt":"2022-04-16T22:33:17","slug":"populacao-de-itabaianinha-na-bronca-com-danilo-e-thiago-de-joaldo","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2022\/04\/16\/populacao-de-itabaianinha-na-bronca-com-danilo-e-thiago-de-joaldo\/","title":{"rendered":"Popula\u00e7\u00e3o de Itabaianinha na bronca com Danilo e Thiago de Joaldo"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Na \u00faltima quinta-feira, 14, segundo circulou nas redes sociais, a popula\u00e7\u00e3o de Tomar do Geru apresentou descontentamento pela ocasi\u00e3o da n\u00e3o realiza\u00e7\u00e3o da tradicional entrega de peixes que seria executada pela Prefeitura. A situa\u00e7\u00e3o ganhou ainda mais repercuss\u00e3o, por conta do prefeito de Itabaianinha, Danilo de Joaldo, fazer entrega do alimento em Geru, juntamente com um ex-vereador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Danilo de Joaldo dirigiu-se \u00e0 cidade vizinha para entregar o peixe da Semana Santa, e esteve acompanhado do ex-vereador Renilson de Berro Grosso. A iniciativa do prefeito e do ex-vereador causou um certo desconforto entre a administra\u00e7\u00e3o de Tomar do Geru e a sua popula\u00e7\u00e3o, por se tratar de um administrador de outra cidade a vir prestar esse aux\u00edlio \u00e0s fam\u00edlias geruenses nesta data santa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por outro lado, tamb\u00e9m emergiram cr\u00edticas por parte dos populares de Itabaianinha, onde surgiram relatos de que na entrega de peixes dentro da pr\u00f3pria cidade, pessoas ficaram sem receber o mantimento, ainda que tivessem recebido as senhas. Com isso, enquanto os moradores de Tomar do Geru ficaram agradecidos pela atitude de Danilo de Joaldo, uma parte dos habitantes de Itabaianinha ficaram na bronca com a gest\u00e3o por ter focado na contribui\u00e7\u00e3o com outra cidade, mas n\u00e3o n\u00e3o cumprindo com as obriga\u00e7\u00f5es no pr\u00f3prio territ\u00f3rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um detalhe que pode explicar esse acontecimento inusitado que gerou tanta pol\u00eamica, \u00e9 que o irm\u00e3o do prefeito de Itabaianinha, Thiago de Joaldo (PP), \u00e9 pr\u00e9-candidato a deputado federal. Ser\u00e1 que teremos uma campanha estadual as custas dos impostos da popula\u00e7\u00e3o de Itabaianinha?<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima quinta-feira, 14, segundo circulou nas redes sociais, a popula\u00e7\u00e3o de Tomar do Geru apresentou descontentamento pela ocasi\u00e3o da n\u00e3o realiza\u00e7\u00e3o da tradicional entrega de peixes que seria executada pela Prefeitura. A situa\u00e7\u00e3o ganhou ainda mais repercuss\u00e3o, por conta do prefeito de Itabaianinha, Danilo de Joaldo, fazer entrega do alimento em Geru, juntamente com [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":2078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-2077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-politica"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2022\/04\/0568210C-64EC-4AF8-A154-B15EF4AA56C3.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2077"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2077\/revisions"}],"predecessor-version":[{"id":2079,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2077\/revisions\/2079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/2078"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}