{"id":2301,"date":"2022-08-01T08:40:49","date_gmt":"2022-08-01T11:40:49","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=2301"},"modified":"2022-08-01T08:40:52","modified_gmt":"2022-08-01T11:40:52","slug":"homem-e-preso-em-flagrante-por-comercio-de-drogas-ilicitas-em-lagarto","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2022\/08\/01\/homem-e-preso-em-flagrante-por-comercio-de-drogas-ilicitas-em-lagarto\/","title":{"rendered":"Homem \u00e9 preso em flagrante por com\u00e9rcio de drogas il\u00edcitas em Lagarto"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Na manh\u00e3 do \u00faltimo s\u00e1bado, 30, um homem identificado como Rafael foi preso em flagrante pelo crime de tr\u00e1fico de drogas, no bairro Alto da Boa Vista, em Lagarto, durante uma opera\u00e7\u00e3o conjunta entre a Pol\u00edcia Civil e a Guarda Municipal. Segundo as autoridades, ele armazenava quatro tipos de drogas il\u00edcitas em sua resid\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, ele&nbsp; \u2013 que era investigado pela pr\u00e1tica delitiva associada a outros traficantes que foram presos durante uma opera\u00e7\u00e3o realizada nesta semana em Lagarto \u2013 confessou que adquiriu as drogas para realizar a revenda, chegando a detalhar por quanto vendia cada unidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<a href=\"http:\/\/A pris\u00e3o de hoje ainda \u00e9 continuidade dos trabalhos realizados durante a semana.\">A pris\u00e3o de hoje ainda \u00e9 continuidade dos trabalhos realizados durante a semana<\/a>. No curso das investiga\u00e7\u00f5es que culminaram na opera\u00e7\u00e3o deflagrada, Rafael figurou como personagem ass\u00edduo na trafic\u00e2ncia local, conduta que praticava associado a outras pessoas, dentre os quais, Anderson, preso na mais recente opera\u00e7\u00e3o em cumprimento a Mandado de Pris\u00e3o Preventiva\u201d, destacou o Delegado Weliton J\u00fanior, respons\u00e1vel pela Divis\u00e3o de Narc\u00f3ticos da Delegacia Regional de Lagarto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o Coordenador Operacional da Guarda Municipal de Lagarto, durante a a\u00e7\u00e3o, foram apreendidas por\u00e7\u00f5es fracionadas de maconha, coca\u00edna, crack e ecstasy, al\u00e9m de apetrechos e subst\u00e2ncia porosa branca comumente utilizados para manipula\u00e7\u00e3o, fracionamento e mistura das droga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cJ\u00e1 na Delegacia, ap\u00f3s consulta ao imei do aparelho celular apreendido em poder do conduzido, verificou-se restri\u00e7\u00e3o por roubo, com Boletim de Ocorr\u00eancia vinculado a assalto ocorrido na capital sergipana, raz\u00e3o pela qual Rafael tamb\u00e9m foi autuado por recepta\u00e7\u00e3o pelo delegado plantonista, sendo o procedimento enviado \u00e0 Justi\u00e7a e o preso encaminhado \u00e0 audi\u00eancia de cust\u00f3dia\u201d, acrescentou a GML.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte : Lagartense <\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 do \u00faltimo s\u00e1bado, 30, um homem identificado como Rafael foi preso em flagrante pelo crime de tr\u00e1fico de drogas, no bairro Alto da Boa Vista, em Lagarto, durante uma opera\u00e7\u00e3o conjunta entre a Pol\u00edcia Civil e a Guarda Municipal. Segundo as autoridades, ele armazenava quatro tipos de drogas il\u00edcitas em sua resid\u00eancia. Al\u00e9m [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":2302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2022\/08\/35886F47-B20A-4E1C-9934-E7DE7B5A6273.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2301"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2301\/revisions"}],"predecessor-version":[{"id":2303,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2301\/revisions\/2303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/2302"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}