{"id":2406,"date":"2022-09-08T10:56:54","date_gmt":"2022-09-08T13:56:54","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=2406"},"modified":"2022-09-08T10:56:55","modified_gmt":"2022-09-08T13:56:55","slug":"diego-costa-vai-assinar-por-uma-temporada-com-o-wolverhampton","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2022\/09\/08\/diego-costa-vai-assinar-por-uma-temporada-com-o-wolverhampton\/","title":{"rendered":"Diego Costa vai assinar por uma temporada com o Wolverhampton"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Livre no mercado da bola desde janeiro de 2022, quando rescindiu contrato com o Atl\u00e9tico-MG, Diego Costa vai ser refor\u00e7o do Wolverhampton. Tem em m\u00e3os para assinar um v\u00ednculo v\u00e1lido por uma temporada (at\u00e9 junho de 2023). A contrata\u00e7\u00e3o depende apenas da realiza\u00e7\u00e3o dos exames m\u00e9dicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De volta ao futebol ingl\u00eas, onde teve destaque no Chelsea, entre 2014 e 2017, o atacante hispano-brasileiro acertou ainda um pr\u00e9-acordo para discutir uma renova\u00e7\u00e3o autom\u00e1tica, a depender de objetivos alcan\u00e7ados, por mais uma temporada com o Wolves (at\u00e9 junho de 2024).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos \u00faltimos meses, o experiente goleador foi alvo de diversas sondagens e ofertas. V\u00e1rios mercados estiveram interessados no jogador. Chegou, por exemplo, a conversar com o Corinthians e tamb\u00e9m a ter recentemente uma negocia\u00e7\u00e3o engatilhada com o Rayo Vallecano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aos 33 anos, Diego Costa caminha ent\u00e3o para representar o d\u00e9cimo clube na vitoriosa carreira. Passou antes por Penafiel, Braga, Celta de Vigo, Albacete, Valladolid, Rayo Vallecano, Atl\u00e9tico de Madrid, Chelsea e Atl\u00e9tico-MG.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: UOL Espporte<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Livre no mercado da bola desde janeiro de 2022, quando rescindiu contrato com o Atl\u00e9tico-MG, Diego Costa vai ser refor\u00e7o do Wolverhampton. Tem em m\u00e3os para assinar um v\u00ednculo v\u00e1lido por uma temporada (at\u00e9 junho de 2023). A contrata\u00e7\u00e3o depende apenas da realiza\u00e7\u00e3o dos exames m\u00e9dicos. De volta ao futebol ingl\u00eas, onde teve destaque no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[47],"class_list":["post-2406","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-destaque"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2406"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2406\/revisions"}],"predecessor-version":[{"id":2408,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2406\/revisions\/2408"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}