{"id":2508,"date":"2022-10-05T18:16:17","date_gmt":"2022-10-05T21:16:17","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=2508"},"modified":"2022-10-05T18:16:19","modified_gmt":"2022-10-05T21:16:19","slug":"delegado-da-policia-civil-sofre-acidente-e-fica-preso-as-ferragens","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2022\/10\/05\/delegado-da-policia-civil-sofre-acidente-e-fica-preso-as-ferragens\/","title":{"rendered":"Delegado da Pol\u00edcia Civil sofre acidente e fica preso \u00e0s ferragens"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Nesta quarta-feira, 05, o delegado da Policia Civil de Umba\u00faba, Rafael Brito, sofreu um grave acidente na rodovia que liga Boquim a Arau\u00e1, mais precisamente, no trevo que &nbsp;d\u00e1 acesso a Arau\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O carro em que o delegado estava bateu em um caminh\u00e3o. De acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica de Sergipe (SSP) o delegado est\u00e1 consciente e com o bra\u00e7o preso \u00e0s ferragens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu), o Corpo de Bombeiros e o Grupamento T\u00e1tico A\u00e9reo (GTA) foram acionados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte:  Lagartense <\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira, 05, o delegado da Policia Civil de Umba\u00faba, Rafael Brito, sofreu um grave acidente na rodovia que liga Boquim a Arau\u00e1, mais precisamente, no trevo que &nbsp;d\u00e1 acesso a Arau\u00e1. O carro em que o delegado estava bateu em um caminh\u00e3o. De acordo com informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica de Sergipe (SSP) [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":2509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2022\/10\/62DF016B-314C-4941-99FF-1A720951876A.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2508"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2508\/revisions"}],"predecessor-version":[{"id":2510,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2508\/revisions\/2510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/2509"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}