{"id":3004,"date":"2023-06-05T18:18:40","date_gmt":"2023-06-05T21:18:40","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=3004"},"modified":"2023-06-05T18:18:41","modified_gmt":"2023-06-05T21:18:41","slug":"jovem-de-20-anos-mata-a-mae-a-facadas-em-lagarto","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2023\/06\/05\/jovem-de-20-anos-mata-a-mae-a-facadas-em-lagarto\/","title":{"rendered":"Jovem de 20 anos mata a m\u00e3e a facadas em Lagarto"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Uma jovem de 20 anos matou a m\u00e3e na tarde desta segunda-feira, 5, no bairro no Bairro Ademar de Carvalho, no munic\u00edpio de Lagarto, regi\u00e3o Centro-Sul de Sergipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Secretaria de Seguran\u00e7a P\u00fablica de Sergipe (SSP\/SE), a mulher foi morta a facadas e, logo ap\u00f3s o crime, a suspeita foi encaminhada \u00e0 Delegacia Regional de Lagarto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A SSP disse que o flagrante est\u00e1 em andamento e que ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre as circunst\u00e2ncia do crime. Um inqu\u00e9rito policial ser\u00e1 instaurado para investigar o caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Por Luana Maria e Verlane Est\u00e1cio com informa\u00e7\u00f5es da SSP\/SE<\/em><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Uma jovem de 20 anos matou a m\u00e3e na tarde desta segunda-feira, 5, no bairro no Bairro Ademar de Carvalho, no munic\u00edpio de Lagarto, regi\u00e3o Centro-Sul de Sergipe. De acordo com a Secretaria de Seguran\u00e7a P\u00fablica de Sergipe (SSP\/SE), a mulher foi morta a facadas e, logo ap\u00f3s o crime, a suspeita foi encaminhada \u00e0 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2023\/06\/IMG_0264.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3004"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3004\/revisions"}],"predecessor-version":[{"id":3006,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3004\/revisions\/3006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3005"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}