{"id":3114,"date":"2023-06-27T15:30:01","date_gmt":"2023-06-27T18:30:01","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=3114"},"modified":"2023-06-27T15:30:03","modified_gmt":"2023-06-27T18:30:03","slug":"policia-prende-suspeito-de-agredir-vizinho-com-barra-de-ferro","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2023\/06\/27\/policia-prende-suspeito-de-agredir-vizinho-com-barra-de-ferro\/","title":{"rendered":"Pol\u00edcia prende suspeito de agredir vizinho com barra de ferro"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Policiais da For\u00e7a T\u00e1tica do 1\u00ba Batalh\u00e3o de Pol\u00edcia Militar (1\u00ba BPM) prenderam um homem suspeito de agredir o vizinho com uma barra de ferro no Bairro S\u00e3o Conrado, em Aracaju. O fato aconteceu no \u00faltimo s\u00e1bado, 24, ap\u00f3s a v\u00edtima reclamar do volume abusivo do som do agressor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A equipe policial foi acionada para averiguar a informa\u00e7\u00e3o de que um homem n\u00e3o gostou da reclama\u00e7\u00e3o do seu vizinho, que estava incomodado com o volume de um som, e o atingiu com uma barra de ferro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s ser questionado sobre o fato, o denunciado disse que agrediu o vizinho em leg\u00edtima defesa, depois de ser atacado por ele com uma faca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por outro lado, as pessoas que testemunharam o fato disseram que n\u00e3o foi a primeira vez que o agressor se envolveu em problemas com a vizinhan\u00e7a, devido \u00e0s constantes den\u00fancias de perturba\u00e7\u00e3o do sossego alheio contra ele.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O homem foi encaminhado \u00e0 delegacia para que fossem tomadas as medidas legais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: SSP\/SE<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Policiais da For\u00e7a T\u00e1tica do 1\u00ba Batalh\u00e3o de Pol\u00edcia Militar (1\u00ba BPM) prenderam um homem suspeito de agredir o vizinho com uma barra de ferro no Bairro S\u00e3o Conrado, em Aracaju. O fato aconteceu no \u00faltimo s\u00e1bado, 24, ap\u00f3s a v\u00edtima reclamar do volume abusivo do som do agressor. A equipe policial foi acionada para [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2023\/06\/IMG_7462.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3114"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3114\/revisions"}],"predecessor-version":[{"id":3116,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3114\/revisions\/3116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3115"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}