{"id":3188,"date":"2023-07-07T15:52:17","date_gmt":"2023-07-07T18:52:17","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=3188"},"modified":"2023-07-07T15:52:18","modified_gmt":"2023-07-07T18:52:18","slug":"dois-caminhoneiros-de-campo-do-brito-morrem-em-minas-gerais","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2023\/07\/07\/dois-caminhoneiros-de-campo-do-brito-morrem-em-minas-gerais\/","title":{"rendered":"Dois caminhoneiros de Campo do Brito morrem em Minas Gerais"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Dois caminhoneiros de Campo do Brito, identificados como Jos\u00e9 Pedro, conhecido como Cabur\u00e9, e Luiz, conhecido como Galo Seco, morreram em um acidente na BR-116, entre Governador Valadares e Te\u00f3filo Otoni, em Minas Gerais. O caso envolveu\u00a0tr\u00eas carros e tr\u00eas caminh\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo informa\u00e7\u00f5es, em um dos caminh\u00f5es, modelo Mercedes-Benz Atego e placas de Campo do Brito, estavam os dois caminhoneiros do munic\u00edpio sergipano. Segundo pessoas pr\u00f3ximas a eles, um morreu carbonizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, militares informaram que uma mulher que estava em um dos carros tamb\u00e9m faleceu no local, enquanto duas pessoas tiveram ferimentos graves e foram levadas em ambul\u00e2ncias do Corpo de Bombeiros para o hospital de Governador Valadares. Outras v\u00edtimas envolvidas no acidente, que apresentavam ferimentos leves, foram socorridas por ambul\u00e2ncias do SAMU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 as causas do acidente ainda s\u00e3o desconhecidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Dois caminhoneiros de Campo do Brito, identificados como Jos\u00e9 Pedro, conhecido como Cabur\u00e9, e Luiz, conhecido como Galo Seco, morreram em um acidente na BR-116, entre Governador Valadares e Te\u00f3filo Otoni, em Minas Gerais. O caso envolveu\u00a0tr\u00eas carros e tr\u00eas caminh\u00f5es. Segundo informa\u00e7\u00f5es, em um dos caminh\u00f5es, modelo Mercedes-Benz Atego e placas de Campo do [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2023\/07\/IMG_1458.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3188"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3188\/revisions"}],"predecessor-version":[{"id":3190,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3188\/revisions\/3190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3189"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}