{"id":3221,"date":"2023-07-13T12:51:02","date_gmt":"2023-07-13T15:51:02","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=3221"},"modified":"2023-07-13T12:51:04","modified_gmt":"2023-07-13T15:51:04","slug":"homem-e-alvejado-e-tem-moto-roubada-na-zona-rural-de-riachao-do-dantas","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2023\/07\/13\/homem-e-alvejado-e-tem-moto-roubada-na-zona-rural-de-riachao-do-dantas\/","title":{"rendered":"Homem \u00e9 alvejado e tem moto roubada na zona rural de Riach\u00e3o do Dantas"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Na noite da \u00faltima quarta-feira, 12, um homem foi alvejado por disparos de arma de fogo e ainda teve sua motocicleta roubada no povoado Campestre, na zona rural de Riach\u00e3o do Dantas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo informa\u00e7\u00f5es, dois suspeitos em uma moto efetuaram disparos em dire\u00e7\u00e3o a v\u00edtima, que foi atingida no bra\u00e7o esquerdo por um dos disparos, e ainda teve sua moto levada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Militar, por sua vez, n\u00e3o conseguiu identificar os suspeitos e nem a motocicleta utilizada por eles devido \u00e0 baixa luminosidade do local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Lagartense <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Na noite da \u00faltima quarta-feira, 12, um homem foi alvejado por disparos de arma de fogo e ainda teve sua motocicleta roubada no povoado Campestre, na zona rural de Riach\u00e3o do Dantas. Segundo informa\u00e7\u00f5es, dois suspeitos em uma moto efetuaram disparos em dire\u00e7\u00e3o a v\u00edtima, que foi atingida no bra\u00e7o esquerdo por um dos disparos, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2023\/07\/IMG_1074.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3221"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3221\/revisions"}],"predecessor-version":[{"id":3223,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3221\/revisions\/3223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3222"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}