{"id":3351,"date":"2024-03-22T10:11:57","date_gmt":"2024-03-22T13:11:57","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3351"},"modified":"2024-03-22T10:11:58","modified_gmt":"2024-03-22T13:11:58","slug":"pm-prende-suspeito-de-ameacar-a-companheira-com-uma-faca-na-zona-sul","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/03\/22\/pm-prende-suspeito-de-ameacar-a-companheira-com-uma-faca-na-zona-sul\/","title":{"rendered":"PM prende suspeito de amea\u00e7ar a companheira com uma faca na Zona Sul"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Equipes do Pelot\u00e3o de Pol\u00edcia Ambiental (PPAmb) prenderam um homem suspeito de amea\u00e7ar a pr\u00f3pria companheira com uma faca no Bairro Para\u00edso do Sul. O crime foi registrado nessa quarta-feira, 20.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Policiais do PPAmb foram acionados por populares para verifica\u00e7\u00e3o da informa\u00e7\u00e3o de que um homem teria agredido verbalmente e amea\u00e7ado a companheira com uma faca, durante uma confraterniza\u00e7\u00e3o com a presen\u00e7a de amigos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o relato, ap\u00f3s ser contido pelas testemunhas, o suspeito seguiu para a resid\u00eancia do casal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No momento em que tentava sair do im\u00f3vel, o homem foi flagrado em posse da faca utilizada para praticar as amea\u00e7as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O suspeito resistiu \u00e0 abordagem, mas foi contido pela a\u00e7\u00e3o policial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao receber voz de pris\u00e3o, ele continuou com as amea\u00e7as, afirmando que deveria ter matado a v\u00edtima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O homem foi encaminhado \u00e0 delegacia para a formaliza\u00e7\u00e3o do flagrante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Equipes do Pelot\u00e3o de Pol\u00edcia Ambiental (PPAmb) prenderam um homem suspeito de amea\u00e7ar a pr\u00f3pria companheira com uma faca no Bairro Para\u00edso do Sul. O crime foi registrado nessa quarta-feira, 20. Policiais do PPAmb foram acionados por populares para verifica\u00e7\u00e3o da informa\u00e7\u00e3o de que um homem teria agredido verbalmente e amea\u00e7ado a companheira com uma [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/03\/IMG_5715.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3351"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3351\/revisions"}],"predecessor-version":[{"id":3353,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3351\/revisions\/3353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3352"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}