{"id":3366,"date":"2024-03-25T16:59:28","date_gmt":"2024-03-25T19:59:28","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3366"},"modified":"2024-04-01T09:46:37","modified_gmt":"2024-04-01T12:46:37","slug":"padre-inaldo-fortalece-parcerias-em-brasilia-em-prol-de-melhorias-para-socorro","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/03\/25\/padre-inaldo-fortalece-parcerias-em-brasilia-em-prol-de-melhorias-para-socorro\/","title":{"rendered":"Padre Inaldo fortalece parcerias em Bras\u00edlia em prol de melhorias para Socorro"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">O prefeito de Nossa Senhora do Socorro, Padre Inaldo (PP), vem desempenhando um papel crucial na busca por melhorias e investimentos em seu munic\u00edpio, consolidando sua gest\u00e3o e abrindo caminho para seu poss\u00edvel sucessor nas elei\u00e7\u00f5es de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recentemente, o gestor intensificou suas atividades com uma s\u00e9rie de visitas estrat\u00e9gicas e reuni\u00f5es produtivas em Bras\u00edlia. Durante esses encontros, ele obteve apoio e recursos para projetos essenciais em Nossa Senhora do Socorro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma das articula\u00e7\u00f5es mais significativas foi com o ministro M\u00e1rcio Macedo, visando apoio para projetos de infraestrutura e capta\u00e7\u00e3o de recursos para as demandas administrativas do munic\u00edpio, encaminhados ao Governo Federal por meio do Programa de Acelera\u00e7\u00e3o do Crescimento (PAC).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo de sua gest\u00e3o, diversas obras foram realizadas, incluindo a constru\u00e7\u00e3o de creches, reforma de escolas e unidades b\u00e1sicas de sa\u00fade, al\u00e9m da implanta\u00e7\u00e3o da primeira Unidade de Pronto Atendimento (UPA) do munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com esse hist\u00f3rico de realiza\u00e7\u00f5es na cidade, Padre Inaldo naturalmente tem uma posi\u00e7\u00e3o vantajosa para fazer um sucessor. Somado a isso, sua pr\u00e9-candidata Carminha Paiva (Republicanos), que \u00e9 reconhecida por seu trabalho social na comunidade, ganha favoritismo e surge como um forte nome para dar continuidade ao legado iniciado pelo atual gestor.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/03\/9bc723c4-2f54-436a-9f1f-06f6dc015b7f-768x1024.jpeg\" alt=\"\" class=\"wp-image-3382\" srcset=\"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/03\/9bc723c4-2f54-436a-9f1f-06f6dc015b7f-768x1024.jpeg 768w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/03\/9bc723c4-2f54-436a-9f1f-06f6dc015b7f-225x300.jpeg 225w, https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/03\/9bc723c4-2f54-436a-9f1f-06f6dc015b7f.jpeg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>O prefeito de Nossa Senhora do Socorro, Padre Inaldo (PP), vem desempenhando um papel crucial na busca por melhorias e investimentos em seu munic\u00edpio, consolidando sua gest\u00e3o e abrindo caminho para seu poss\u00edvel sucessor nas elei\u00e7\u00f5es de 2024. Recentemente, o gestor intensificou suas atividades com uma s\u00e9rie de visitas estrat\u00e9gicas e reuni\u00f5es produtivas em Bras\u00edlia. [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-3366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/03\/18fa28ab-fb98-4764-9b9b-9c7dbfb44c24.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3366"}],"version-history":[{"count":2,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3366\/revisions"}],"predecessor-version":[{"id":3383,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3366\/revisions\/3383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3367"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}