{"id":3384,"date":"2024-03-27T10:22:24","date_gmt":"2024-03-27T13:22:24","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3384"},"modified":"2024-03-27T10:22:25","modified_gmt":"2024-03-27T13:22:25","slug":"meteorologia-indica-possibilidade-de-chuvas-e-trovoadas-em-sergipe","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/03\/27\/meteorologia-indica-possibilidade-de-chuvas-e-trovoadas-em-sergipe\/","title":{"rendered":"Meteorologia indica possibilidade de chuvas e trovoadas em Sergipe"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Secretaria de Estado do Meio Ambiente, Sustentabilidade e A\u00e7\u00f5es Clim\u00e1ticas (Semac) emitiu um alerta meteorol\u00f3gico, indicando a probabilidade de chuvas e ventos intensos, acompanhados de trovoadas e descargas el\u00e9tricas entre esta quinta, 28, e sexta-feira, 29.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme o alerta, a previs\u00e3o aponta um acumulado de chuvas maior que 70mm\/dia, al\u00e9m de ventos intensos entre 40 e 60 km\/h. O boletim tamb\u00e9m indica a probabilidade de trovoadas e descargas el\u00e9tricas em todo o estado, com possibilidade de chuva de granizo no Agreste e Sert\u00e3o sergipano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a Semac, os fen\u00f4menos das Ondas de Leste (DOL) e da Zona de Converg\u00eancia Intertropical (ZCIT) atuam no transporte de nuvens convectivas para o estado de Sergipe. Al\u00e9m disso, devido \u00e0s altas temperaturas e a umidade nos n\u00edveis da atmosfera, h\u00e1 uma grande probabilidade do desenvolvimento de nuvens de grande desenvolvimento vertical (CBs), ocasionando chuvas intensas em Sergipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alerta<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ocorr\u00eancia de chuvas pode gerar acumulados expressivos para o estado de Sergipe, apresentando riscos em rodovias, de alagamentos, de deslizamentos de encostas. Tamb\u00e9m risco de transbordamento de pequenos c\u00f3rregos, riachos e dos principais rios e lagoas do estado de Sergipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Por Carol Mundim e Verlane Est\u00e1cio<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado do Meio Ambiente, Sustentabilidade e A\u00e7\u00f5es Clim\u00e1ticas (Semac) emitiu um alerta meteorol\u00f3gico, indicando a probabilidade de chuvas e ventos intensos, acompanhados de trovoadas e descargas el\u00e9tricas entre esta quinta, 28, e sexta-feira, 29.&nbsp; Conforme o alerta, a previs\u00e3o aponta um acumulado de chuvas maior que 70mm\/dia, al\u00e9m de ventos intensos entre [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":3385,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/03\/IMG_5800.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3384"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3384\/revisions"}],"predecessor-version":[{"id":3386,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3384\/revisions\/3386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3385"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}