{"id":3419,"date":"2024-04-05T16:22:59","date_gmt":"2024-04-05T19:22:59","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3419"},"modified":"2024-04-05T16:23:00","modified_gmt":"2024-04-05T19:23:00","slug":"em-maior-expulsao-de-uma-vez-so-paraguai-envia-25-presos-brasileiros-para-o-brasil","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/04\/05\/em-maior-expulsao-de-uma-vez-so-paraguai-envia-25-presos-brasileiros-para-o-brasil\/","title":{"rendered":"Em maior expuls\u00e3o de uma vez s\u00f3, Paraguai envia 25 presos brasileiros para o Brasil"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">O governo do Paraguai expulsou 25 brasileiros que estavam presos no pa\u00eds e que tamb\u00e9m eram procurados pela Justi\u00e7a brasileira, acusados de crimes como homic\u00eddio, tr\u00e1fico de drogas e associa\u00e7\u00e3o criminosa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os homens foram entregues na quinta-feira (4) \u00e0&nbsp;<a class=\"\" href=\"https:\/\/g1.globo.com\/tudo-sobre\/policia-federal\/\">Pol\u00edcia Federal<\/a>&nbsp;em dois pontos da divisa, no Mato Grosso do Sul e no Paran\u00e1, e agora v\u00e3o cumprir pena no Brasil.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fontes da Pol\u00edcia Federal ouvidas pela TV Globo informaram que a expuls\u00e3o de criminosos brasileiros pelo Paraguai ocorre com frequ\u00eancia. Entretanto, nunca havia sido expulso um n\u00famero t\u00e3o grande de uma \u00fanica vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No ano passado, a PF enviou ao Paraguai t\u00e9cnicos que fizeram a identifica\u00e7\u00e3o de todos os brasileiros presos em penitenci\u00e1rias paraguaias. S\u00e3o cerca de 300 cumprindo pena no pa\u00eds vizinho, e alguns deles estavam usando nomes falsos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a identifica\u00e7\u00e3o, a Pol\u00edcia Federal conseguiu localizar cerca de 50 pessoas que tamb\u00e9m eram procurados pela Justi\u00e7a brasileira. Os 25 considerados mais perigosos, e condenados por crimes como homic\u00eddio e tr\u00e1fico de drogas, foram enviados para o Brasil na quinta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um desses criminosos tem condena\u00e7\u00f5es no Brasil cujas penas somam 57 anos de pris\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos 25 detentos, 16 foram entregues pelas autoridades paraguaias em Foz do Igua\u00e7u (PR). Os outros nove chegaram via Ponta Por\u00e3 (MS).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eles ser\u00e3o agora encaminhados para cumprimento de penas em estados como SP, MG, RS, GO e RN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte:G1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>O governo do Paraguai expulsou 25 brasileiros que estavam presos no pa\u00eds e que tamb\u00e9m eram procurados pela Justi\u00e7a brasileira, acusados de crimes como homic\u00eddio, tr\u00e1fico de drogas e associa\u00e7\u00e3o criminosa.&nbsp; Os homens foram entregues na quinta-feira (4) \u00e0&nbsp;Pol\u00edcia Federal&nbsp;em dois pontos da divisa, no Mato Grosso do Sul e no Paran\u00e1, e agora v\u00e3o [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/04\/IMG_5979.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3419"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3419\/revisions"}],"predecessor-version":[{"id":3421,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3419\/revisions\/3421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3420"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}