{"id":3444,"date":"2024-04-13T11:09:58","date_gmt":"2024-04-13T14:09:58","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3444"},"modified":"2024-04-13T11:10:00","modified_gmt":"2024-04-13T14:10:00","slug":"acao-integrada-localiza-suspeito-de-furto-de-motocicleta-em-riachao-do-dantas","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/04\/13\/acao-integrada-localiza-suspeito-de-furto-de-motocicleta-em-riachao-do-dantas\/","title":{"rendered":"A\u00e7\u00e3o integrada localiza suspeito de furto de motocicleta em Riach\u00e3o do Dantas"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Na \u00faltima sexta-feira, 12, policiais militares de Riach\u00e3o do Dantas deram cumprimento ao mandado de pris\u00e3o contra um suspeito de furto de motocicleta. A a\u00e7\u00e3o aconteceu ap\u00f3s investiga\u00e7\u00e3o da Pol\u00edcia Civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois de den\u00fancias das v\u00edtimas dos furtos, a Delegacia de Riach\u00e3o do Dantas iniciou&nbsp;dilig\u00eancias, no sentido de localizar o respons\u00e1vel pelos&nbsp;crimes. Com a an\u00e1lise de imagens registradas por c\u00e2meras de seguran\u00e7a, somada&nbsp;\u00e0s ouvidas de testemunhas que presenciaram os delitos, a Pol\u00edcia Civil chegou \u00e0 identidade do suspeito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em meio aos levantamentos, a Pol\u00edcia Civil apurou&nbsp;que o suspeito j\u00e1 tinha um hist\u00f3rico criminal, sendo reincidente no&nbsp;crime de furto,&nbsp;no mesmo munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com isso, foi representada a pris\u00e3o preventiva do homem, sendo acolhida pela Justi\u00e7a. Na sexta-feira, 12, a PM localizou o investigado e cumpriu a determina\u00e7\u00e3o judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O suspeito&nbsp;foi encaminhado \u00e0 Delegacia de Riach\u00e3o do Dantas e est\u00e1 \u00e0 disposi\u00e7\u00e3o do Poder Judici\u00e1rio.<br>A Pol\u00edcia Civil relembra a import\u00e2ncia da popula\u00e7\u00e3o de Riach\u00e3o do Dantas&nbsp;denunciar crimes atrav\u00e9s do Disque-Den\u00fancia (181). O sigilo do (a) denunciante \u00e9 garantido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: SSP\/SE<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima sexta-feira, 12, policiais militares de Riach\u00e3o do Dantas deram cumprimento ao mandado de pris\u00e3o contra um suspeito de furto de motocicleta. A a\u00e7\u00e3o aconteceu ap\u00f3s investiga\u00e7\u00e3o da Pol\u00edcia Civil. Depois de den\u00fancias das v\u00edtimas dos furtos, a Delegacia de Riach\u00e3o do Dantas iniciou&nbsp;dilig\u00eancias, no sentido de localizar o respons\u00e1vel pelos&nbsp;crimes. Com a an\u00e1lise [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/04\/policiacivil_ilustrativa-1-1024x575-2-741x486-1.jpg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3444"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3444\/revisions"}],"predecessor-version":[{"id":3446,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3444\/revisions\/3446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3445"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}