{"id":3447,"date":"2024-04-13T11:13:18","date_gmt":"2024-04-13T14:13:18","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3447"},"modified":"2024-04-13T11:13:19","modified_gmt":"2024-04-13T14:13:19","slug":"corpo-carbonizado-e-encontrado-embaixo-de-ponte-na-coroa-do-meio","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/04\/13\/corpo-carbonizado-e-encontrado-embaixo-de-ponte-na-coroa-do-meio\/","title":{"rendered":"Corpo carbonizado \u00e9 encontrado embaixo de ponte na Coroa do Meio"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um corpo carbonizado foi encontrado dentro de um carrinho de supermercado embaixo da ponte Godofredo Diniz, no bairro Coroa do Meio. O cad\u00e1ver foi encontrado no fim da tarde desta sexta-feira, 12.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a Pol\u00edcia Militar (PM), a equipe policial foi acionada para atender uma ocorr\u00eancia de encontro de cad\u00e1ver. Chegando ao local indicado, que era de dif\u00edcil acesso, encontraram o corpo sem sinais de vida, sem vestes e sem documentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante do ocorrido, os policiais isolaram a \u00e1rea e acionaram a per\u00edcia t\u00e9cnica e o Instituto M\u00e9dico Legal (IML) para que fossem realizadas as medidas cab\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um corpo carbonizado foi encontrado dentro de um carrinho de supermercado embaixo da ponte Godofredo Diniz, no bairro Coroa do Meio. O cad\u00e1ver foi encontrado no fim da tarde desta sexta-feira, 12. Segundo a Pol\u00edcia Militar (PM), a equipe policial foi acionada para atender uma ocorr\u00eancia de encontro de cad\u00e1ver. Chegando ao local indicado, que [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3449,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/04\/pontecoroadomeio_fotomarcellecristinne_230522-1-357x210-1.jpg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3447"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3447\/revisions"}],"predecessor-version":[{"id":3450,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3447\/revisions\/3450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3449"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}