{"id":3455,"date":"2024-04-18T14:17:29","date_gmt":"2024-04-18T17:17:29","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3455"},"modified":"2024-04-18T14:17:31","modified_gmt":"2024-04-18T17:17:31","slug":"seis-mandados-de-prisao-sao-cumpridos-em-sergipe-e-bahia-durante-operacao-contra-grupo-de-estelionatarios","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/04\/18\/seis-mandados-de-prisao-sao-cumpridos-em-sergipe-e-bahia-durante-operacao-contra-grupo-de-estelionatarios\/","title":{"rendered":"Seis mandados de pris\u00e3o s\u00e3o cumpridos em Sergipe e Bahia durante opera\u00e7\u00e3o contra grupo de estelionat\u00e1rios"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Seis mandados de pris\u00e3o foram cumpridos na manh\u00e3 desta quinta-feira (18), em cidades da regi\u00e3o Centro-Sul de Sergipe e Bahia, durante a Opera\u00e7\u00e3o Divisa 171, que visa o cumprimento de mandados de pris\u00e3o preventiva e de busca e apreens\u00e3o domiciliar contra grupo suspeito de praticar crimes de estelionato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado da opera\u00e7\u00e3o, a Pol\u00edcia Civil detalhou que um mandado de pris\u00e3o foi cumprido no Pres\u00eddio de Est\u00e2ncia, al\u00e9m de dois mandados de pris\u00e3o preventiva em Sim\u00e3o Dias. Al\u00e9m disso, um mandado de pris\u00e3o preventiva foi cumprido em Antas e dois mandados de pris\u00e3o e oito de buscas cumpridos no Pres\u00eddio de Paulo Afonso, na Bahia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O grupo criminoso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo as investiga\u00e7\u00f5es policiais, a organiza\u00e7\u00e3o criminosa \u00e9 formada por internos do Conjunto Penal de Paulo Afonso e por pessoas que estavam em liberdade atuando em Sim\u00e3o Dias e regi\u00e3o. Os suspeitos realizavam transa\u00e7\u00f5es fraudulentas de bens ofertados em sites de vendas e redes sociais em munic\u00edpios de Sergipe e Bahia. Eles buscavam por bens, como ve\u00edculos, celulares e sistemas de som automotivo, anunciados em plataformas de vendas online ou em redes sociais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo a Pol\u00edcia Civil, para obter \u00eaxito na a\u00e7\u00e3o os investigados se passavam por policiais militares ou civis e, at\u00e9 mesmo, como policiais rodovi\u00e1rios federais,a fim denegociar a compra dos itens de interesse. Ap\u00f3s a compra, os criminosos enviavam falsos comprovantes banc\u00e1rios de transfer\u00eancias \u00e0s v\u00edtimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os levantamentos da Delegacia de Sim\u00e3o Dias apontaram que os investigados cometeram delitos em Sim\u00e3o Dias a mando de um interno do Conjunto Penal de Paulo Afonso. Este interno ordenava que os criminosos pegassem motocicletas em determinados locais e as transportassem para diferentes munic\u00edpios da Bahia, onde eram repassadas a terceiros indicados pelo preso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diversas pessoas foram v\u00edtimas destes golpes, tanto por terem os bens levados, tanto por n\u00e3o receberem pelos servi\u00e7os prestados. Al\u00e9m disso, profissionais de boa-f\u00e9 executaram os servi\u00e7o do crime sem saber que estavam compactuando com os criminosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Civil continuar\u00e1 a investiga\u00e7\u00e3o, uma vez que foram encontrados golpes similares nas cidades de Lagarto, Po\u00e7o Verde, em Sergipe, Paripiranga, C\u00edcero Dantas, Antas, F\u00e1tima e Jeremoabo, ambas na Bahia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A opera\u00e7\u00e3o conjunta foi deflagrada pelas Delegacias de Sim\u00e3o Dias, Itaporanga D\u2019Ajuda e Campo do Brito, da Divis\u00e3o de Patrim\u00f4nio da Delegacia Regional de Lagarto, Coordenadoria de Opera\u00e7\u00f5es e Recursos Especiais (Core), Gope da Pol\u00edcia Penal, 4\u00aa Companhia Independente da Pol\u00edcia Militar do Estado de Sergipe, Delegacia de Antas\/BA e Delegacia Territorial de Paulo Afonso\/BA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: A8se<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Seis mandados de pris\u00e3o foram cumpridos na manh\u00e3 desta quinta-feira (18), em cidades da regi\u00e3o Centro-Sul de Sergipe e Bahia, durante a Opera\u00e7\u00e3o Divisa 171, que visa o cumprimento de mandados de pris\u00e3o preventiva e de busca e apreens\u00e3o domiciliar contra grupo suspeito de praticar crimes de estelionato. Como resultado da opera\u00e7\u00e3o, a Pol\u00edcia Civil [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/04\/IMG_6364.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3455"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3455\/revisions"}],"predecessor-version":[{"id":3457,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3455\/revisions\/3457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3456"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}