{"id":3506,"date":"2024-04-30T09:01:06","date_gmt":"2024-04-30T12:01:06","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3506"},"modified":"2024-04-30T09:01:08","modified_gmt":"2024-04-30T12:01:08","slug":"policia-indicia-um-terceiro-motorista-apontado-como-o-causador-do-acidente-com-cinco-mortes-na-se-270","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/04\/30\/policia-indicia-um-terceiro-motorista-apontado-como-o-causador-do-acidente-com-cinco-mortes-na-se-270\/","title":{"rendered":"Pol\u00edcia indicia um terceiro motorista, apontado como o causador do acidente com cinco mortes na SE-270"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Investiga\u00e7\u00f5es da Pol\u00edcia Civil apontaram que um<strong>\u00a0terceiro ve\u00edculo foi o causador\u00a0<\/strong>do acidente que deixou duas mulheres, uma crian\u00e7a, um adolescente e um homem mortos, al\u00e9m de uma crian\u00e7a gravemente ferida\u00a0na SE-270, no munic\u00edpio de Lagarto, no \u00faltimo dia 14 de abril. O motorista deve responder por homic\u00eddio culposo de tr\u00e2nsito.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o delegado Paulo Cristiano, o suspeito foi identificado e levado para prestar depoimento. Todos os ve\u00edculos envolvidos passaram por per\u00edcia criminal. Os laudos ainda n\u00e3o foram conclu\u00eddos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;A pol\u00edcia indiciou o elemento que dirigia o terceiro ve\u00edculo e requisitou junto \u00e0 Justi\u00e7a a aplica\u00e7\u00e3o de medidas cautelares, notadamente a suspens\u00e3o do direito de dirigir&#8221;, disse.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O acidente<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O acidente ocorreu por volta das 23h, quando dois ve\u00edculos bateram de frente, ao serem provocados pelo terceiro. A din\u00e2mica do acidente n\u00e3o foi informada pela pol\u00edcia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seis pessoas estavam em um mesmo ve\u00edculo, sendo que duas morreram no local e as outras quatro ficaram gravemente feridas, incluindo o motorista, e foram levados ao Hospital de Urg\u00eancias de Sergipe. Os outros dois condutores sa\u00edram do local.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No local do acidente morreram Patr\u00edcia dos Santos Silva, de 33 anos, o filho, de 12 anos, e uma jovem de 20 anos, identificada como Milena de Andrade Gon\u00e7alves.<\/li>\n\n\n\n<li>Dois dias depois, o motorista do ve\u00edculo, Jos\u00e9 Silvanio Santana Santos, de 24 anos, morreu no Huse.<\/li>\n\n\n\n<li>No dia 23 de abril,\u00a0morreu, na unidade, um segundo filho de Patr\u00edcia, de 5 anos.<\/li>\n\n\n\n<li>J\u00e1 a filha de Patr\u00edcia, de 11 anos, continua internada no Huse. Segundo a unidade, ela est\u00e1 consciente e orientada, em acompanhamento da especialidade de Cirurgia Pl\u00e1stica.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Investiga\u00e7\u00f5es da Pol\u00edcia Civil apontaram que um\u00a0terceiro ve\u00edculo foi o causador\u00a0do acidente que deixou duas mulheres, uma crian\u00e7a, um adolescente e um homem mortos, al\u00e9m de uma crian\u00e7a gravemente ferida\u00a0na SE-270, no munic\u00edpio de Lagarto, no \u00faltimo dia 14 de abril. O motorista deve responder por homic\u00eddio culposo de tr\u00e2nsito.\u00a0 De acordo com o delegado [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/04\/IMG_6300-1.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3506"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3506\/revisions"}],"predecessor-version":[{"id":3508,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3506\/revisions\/3508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3507"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}