{"id":3522,"date":"2024-04-29T17:00:27","date_gmt":"2024-04-29T20:00:27","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3522"},"modified":"2024-04-30T17:00:51","modified_gmt":"2024-04-30T20:00:51","slug":"policia-divulga-imagens-do-suspeito-de-assalto-a-casa-em-aracaju","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/04\/29\/policia-divulga-imagens-do-suspeito-de-assalto-a-casa-em-aracaju\/","title":{"rendered":"Pol\u00edcia divulga imagens do suspeito de assalto a casa em Aracaju"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A 9\u00aa Delegacia Metropolitana (9\u00aa DM) divulgou imagens do suspeito de roubar aparelhos celulares durante um roubo em uma resid\u00eancia localizada no bairro Santa Maria. O caso ocorreu no \u00faltimo dia 20 de abril, e as imagens foram divulgadas nesta ter\u00e7a-feira, 30.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com as informa\u00e7\u00f5es policiais, por volta do meio-dia do dia 20, um homem \u2013 vestindo cal\u00e7a e camisa de mangas compridas, aparentando entre 20 e 25 anos e com altura estimada em 1,75m \u2013 pediu \u00e1gua a uma pessoa que estava no im\u00f3vel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando a v\u00edtima foi buscar \u00e1gua, o suspeito entrou no im\u00f3vel empunhando um rev\u00f3lver prateado. Ele anunciou o crime e roubou cinco aparelhos celulares das pessoas que estavam no im\u00f3vel. Documentos tamb\u00e9m foram levados<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 9\u00aa Delegacia Metropolitana (9\u00aa DM) divulgou imagens do suspeito de roubar aparelhos celulares durante um roubo em uma resid\u00eancia localizada no bairro Santa Maria. O caso ocorreu no \u00faltimo dia 20 de abril, e as imagens foram divulgadas nesta ter\u00e7a-feira, 30. De acordo com as informa\u00e7\u00f5es policiais, por volta do meio-dia do dia 20, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/04\/IMG_0322.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3522"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3522\/revisions"}],"predecessor-version":[{"id":3524,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3522\/revisions\/3524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3523"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}