{"id":3531,"date":"2024-05-01T17:15:44","date_gmt":"2024-05-01T20:15:44","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3531"},"modified":"2024-05-02T17:16:25","modified_gmt":"2024-05-02T20:16:25","slug":"aracaju-inicia-vacinacao-contra-a-dengue-para-criancas-de-10-a-14-anos-nesta-quinta-feira","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/05\/01\/aracaju-inicia-vacinacao-contra-a-dengue-para-criancas-de-10-a-14-anos-nesta-quinta-feira\/","title":{"rendered":"Aracaju inicia vacina\u00e7\u00e3o contra a dengue para crian\u00e7as de 10 a 14 anos nesta quinta-feira"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aracaju inicia, nesta quinta-feira (2), a vacina\u00e7\u00e3o contra a dengue para crian\u00e7as com idades entre 10 e 14 anos. A informa\u00e7\u00e3o \u00e9 da Secretaria Municipal da Sa\u00fade (SMS), que confirmou o recebimento do Minist\u00e9rio da Sa\u00fade (MS) de 9.833 doses de vacina, inicialmente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2705&nbsp;<a class=\"\" href=\"https:\/\/www.whatsapp.com\/channel\/0029VaAG024I1rcg2PPxlf2e\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui para seguir o canal do g1 SE no WhatsApp<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A vacina \u00e9 administrada em duas doses e, conforme o Minist\u00e9rio da Sa\u00fade, as doses destinadas \u00e0 aplica\u00e7\u00e3o da D2 ser\u00e3o enviadas posteriormente, considerando o intervalo recomendado de tr\u00eas meses para completar o esquema da vacina\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCaso a crian\u00e7a j\u00e1 tenha tomado a D1 e tenha tido dengue, acrescenta 30 dias no tempo para ser tomada a D2, por exemplo, se tomou a D1 h\u00e1 dois meses, conta dois meses para tomar a D2. Caso a crian\u00e7a n\u00e3o tenha iniciado o esquema de vacina\u00e7\u00e3o e teve dengue, aguarda seis meses para tomar a D1. Vale ressaltar que a vacina contra a dengue n\u00e3o pode ser tomada junto com outra vacina\u201d, explica a coordenadora de Imuniza\u00e7\u00e3o da SMS, Larissa Ribeiro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aracaju inicia, nesta quinta-feira (2), a vacina\u00e7\u00e3o contra a dengue para crian\u00e7as com idades entre 10 e 14 anos. A informa\u00e7\u00e3o \u00e9 da Secretaria Municipal da Sa\u00fade (SMS), que confirmou o recebimento do Minist\u00e9rio da Sa\u00fade (MS) de 9.833 doses de vacina, inicialmente.&nbsp; \u2705&nbsp;Clique aqui para seguir o canal do g1 SE no WhatsApp A [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/05\/IMG_0344.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3531"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3531\/revisions"}],"predecessor-version":[{"id":3533,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3531\/revisions\/3533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3532"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}