{"id":3573,"date":"2024-05-14T11:23:19","date_gmt":"2024-05-14T14:23:19","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3573"},"modified":"2024-05-14T11:23:20","modified_gmt":"2024-05-14T14:23:20","slug":"pm-prende-foragido-da-justica-baiana-e-apreende-arma-em-caninde","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/05\/14\/pm-prende-foragido-da-justica-baiana-e-apreende-arma-em-caninde\/","title":{"rendered":"PM prende foragido da justi\u00e7a baiana e apreende arma em Canind\u00e9"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Equipes da For\u00e7a T\u00e1tica do 4\u00ba Batalh\u00e3o da Pol\u00edcia Militar (4\u00ba BPM) prenderam um homem foragido da Justi\u00e7a do Estado da Bahia. Ele foi preso ap\u00f3s amea\u00e7ar vizinhos com uma arma de fogo na cidade de Canind\u00e9 de S\u00e3o Francisco, Alto Sert\u00e3o sergipano. A pris\u00e3o aconteceu na noite desse domingo, 12.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os policiais da For\u00e7a T\u00e1tica foram acionados para intervir em uma ocorr\u00eancia de amea\u00e7a com arma de fogo, no Bairro Olaria. Na resid\u00eancia do suspeito, as equipes do 4\u00ba BPM encontraram uma espingarda e uma motocicleta com sinais de adultera\u00e7\u00e3o no chassi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s consulta ao sistema Infoseg, os militares constataram que havia dois mandados de pris\u00e3o em aberto contra o suspeito, ambos expedidos pela Comarca de Paulo Afonso. Ele ainda tentou enganar os policiais informando um nome falso, mas com a colabora\u00e7\u00e3o da m\u00e3e do foragido, ele acabou sendo identificado e preso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Equipes da For\u00e7a T\u00e1tica do 4\u00ba Batalh\u00e3o da Pol\u00edcia Militar (4\u00ba BPM) prenderam um homem foragido da Justi\u00e7a do Estado da Bahia. Ele foi preso ap\u00f3s amea\u00e7ar vizinhos com uma arma de fogo na cidade de Canind\u00e9 de S\u00e3o Francisco, Alto Sert\u00e3o sergipano. A pris\u00e3o aconteceu na noite desse domingo, 12. Os policiais da For\u00e7a [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/05\/IMG_6767.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3573"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3573\/revisions"}],"predecessor-version":[{"id":3575,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3573\/revisions\/3575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3574"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}