{"id":3640,"date":"2024-05-25T12:00:31","date_gmt":"2024-05-25T15:00:31","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3640"},"modified":"2024-05-25T12:00:33","modified_gmt":"2024-05-25T15:00:33","slug":"homem-que-se-apresentava-como-rezador-e-preso-por-dopar-casal-de-adolescentes-em-caninde-de-sao-francisco","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/05\/25\/homem-que-se-apresentava-como-rezador-e-preso-por-dopar-casal-de-adolescentes-em-caninde-de-sao-francisco\/","title":{"rendered":"Homem que se apresentava como rezador \u00e9 preso por dopar casal de adolescentes em Canind\u00e9 de S\u00e3o Francisco"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um homem que se apresenta com rezador foi preso suspeito de dopar um casal de adolescentes em\u00a0Canind\u00e9 de S\u00e3o Francisco, ap\u00f3s ter ido \u00e0 casa das v\u00edtimas fazer uma &#8216;reza&#8217;. A informa\u00e7\u00e3o foi confirmada pela Pol\u00edcia Civil nesta sexta-feira ( 24). O suspeito negou envolvimento no crime.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a pol\u00edcia, o casal compareceu \u00e0 delegacia acompanhados pelo Conselho Tutelar e parentes. Os dois adolescentes estavam em p\u00e9ssimas condi\u00e7\u00f5es de sa\u00fade, principalmente o rapaz. Os dois foram levados ao hospital e ficaram internados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda segundo a pol\u00edcia, a per\u00edcia inicial feita por m\u00e9dicos constatou ind\u00edcios de alguma esp\u00e9cie de calmante no organismo dos jovens. Eles s\u00f3 acordaram 24 horas ap\u00f3s terem sido supostamente dopados pelo investigado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O homem teria for\u00e7ado as duas v\u00edtimas a ingerirem um suco de fruta. Uma das v\u00edtimas afirmou que o investigado estava armado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda de acordo com a pol\u00edcia, o homem possui hist\u00f3rico criminal pelos crimes de tr\u00e1fico de drogas e homic\u00eddio, sendo a sua meia-irm\u00e3 a v\u00edtima do \u00faltimo crime, no munic\u00edpio de Graccho Cardoso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As investiga\u00e7\u00f5es continuam em andamento para identificar outras circunst\u00e2ncias do fato e tamb\u00e9m a motiva\u00e7\u00e3o do investigado. A Pol\u00edcia Civil solicita que informa\u00e7\u00f5es e den\u00fancias sejam repassadas atrav\u00e9s do Disque-Den\u00fancia no telefone 181. O sigilo do denunciante \u00e9 garantido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um homem que se apresenta com rezador foi preso suspeito de dopar um casal de adolescentes em\u00a0Canind\u00e9 de S\u00e3o Francisco, ap\u00f3s ter ido \u00e0 casa das v\u00edtimas fazer uma &#8216;reza&#8217;. A informa\u00e7\u00e3o foi confirmada pela Pol\u00edcia Civil nesta sexta-feira ( 24). O suspeito negou envolvimento no crime.\u00a0 De acordo com a pol\u00edcia, o casal compareceu [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/05\/IMG_6887.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3640"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3640\/revisions"}],"predecessor-version":[{"id":3642,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3640\/revisions\/3642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3641"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}