{"id":3779,"date":"2024-06-17T14:37:44","date_gmt":"2024-06-17T17:37:44","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3779"},"modified":"2024-06-17T14:37:46","modified_gmt":"2024-06-17T17:37:46","slug":"homem-tenta-subornar-policial-em-prol-de-conhecido-e-os-dois-vao-presos-em-pirambu","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/06\/17\/homem-tenta-subornar-policial-em-prol-de-conhecido-e-os-dois-vao-presos-em-pirambu\/","title":{"rendered":"Homem tenta subornar policial em prol de conhecido e os dois v\u00e3o presos em Pirambu"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Por volta das 3h30 do \u00faltimo s\u00e1bado (16), dois indiv\u00edduos foram presos na rodovia SE-100, durante uma blitz na entrada do munic\u00edpio de Pirambu.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O primeiro, um motociclista, foi apreendido por embriaguez e desacato aos agentes de tr\u00e2nsito. J\u00e1 o segundo, foi preso por tentar subornar os policiais para liberarem o motociclista.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo informa\u00e7\u00f5es do Batalh\u00e3o da Pol\u00edcia Rodovi\u00e1ria Estadual (BPRv), o primeiro suspeito foi abordado ap\u00f3s realizar ultrapassagens proibidas a v\u00e1rios ve\u00edculos e negar-se a parar na blitz.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O motociclista avan\u00e7ou contra a guarni\u00e7\u00e3o e acabou sendo rendido pelos policiais. Foi feita a busca pessoal e constatado um odor e comportamentos de embriaguez, confirmado pelos agentes de tr\u00e2nsito.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enquanto o motociclista aguardava o procedimento adiministrativo, o companheiro da sua sobrinha apareceu no local. Ao entender a situa\u00e7\u00e3o, o conhecido ofereceu, mais de uma vez, dinheiro a guarni\u00e7\u00e3o com o intuito de livrar o seu parente do ocorrido, praticando assim o crime de corru\u00e7\u00e3o ativa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os dois indiv\u00edduos foram encaminhados \u00e0 delegacia plantonista do munic\u00edpio de Pirambu, para andamento das medidas legais cab\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: A8se<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Por volta das 3h30 do \u00faltimo s\u00e1bado (16), dois indiv\u00edduos foram presos na rodovia SE-100, durante uma blitz na entrada do munic\u00edpio de Pirambu.&nbsp; O primeiro, um motociclista, foi apreendido por embriaguez e desacato aos agentes de tr\u00e2nsito. J\u00e1 o segundo, foi preso por tentar subornar os policiais para liberarem o motociclista.&nbsp; Segundo informa\u00e7\u00f5es do [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/06\/IMG_7395.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3779"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3779\/revisions"}],"predecessor-version":[{"id":3781,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3779\/revisions\/3781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3780"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}