{"id":3807,"date":"2024-06-20T09:28:37","date_gmt":"2024-06-20T12:28:37","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3807"},"modified":"2024-06-21T09:30:29","modified_gmt":"2024-06-21T12:30:29","slug":"jovem-de-20-anos-morre-ao-colidir-em-onibus-da-cantora-priscila-senna","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/06\/20\/jovem-de-20-anos-morre-ao-colidir-em-onibus-da-cantora-priscila-senna\/","title":{"rendered":"Jovem de 20 anos morre ao colidir em \u00f4nibus da cantora Priscila Senna"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um jovem de 20 anos morreu ao bater a motocicleta em que conduzia com um \u00f4nibus da cantora Priscila Sena. O acidente foi registrado na madrugada desta sexta-feira, 21. A artista se apresentou na noite dessa quinta no \u2018Arrai\u00e1 do Povo\u2019, na Orla da Atalaia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o Batalh\u00e3o de Policiamento de Tr\u00e2nsito (BPTran), o \u00f4nibus seguia pela Av. Gon\u00e7alo Rollemberg e, ao cruzar a Av. Augusto Franco, os ve\u00edculos colidiram transversalmente. O jovem morreu na hora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda de acordo com o BPTran, o condutor da moto n\u00e3o era habilitado, mas o do \u00f4nibus estava em situa\u00e7\u00e3o regular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">fonte: Infonet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um jovem de 20 anos morreu ao bater a motocicleta em que conduzia com um \u00f4nibus da cantora Priscila Sena. O acidente foi registrado na madrugada desta sexta-feira, 21. A artista se apresentou na noite dessa quinta no \u2018Arrai\u00e1 do Povo\u2019, na Orla da Atalaia. Segundo o Batalh\u00e3o de Policiamento de Tr\u00e2nsito (BPTran), o \u00f4nibus [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/06\/IMG_2186.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3807"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3807\/revisions"}],"predecessor-version":[{"id":3809,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3807\/revisions\/3809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3808"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}