{"id":3966,"date":"2024-07-09T15:58:56","date_gmt":"2024-07-09T18:58:56","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=3966"},"modified":"2024-07-09T15:58:58","modified_gmt":"2024-07-09T18:58:58","slug":"inscricoes-para-concurso-publico-da-sergas-sao-prorrogadas-confira-as-datas","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/07\/09\/inscricoes-para-concurso-publico-da-sergas-sao-prorrogadas-confira-as-datas\/","title":{"rendered":"Inscri\u00e7\u00f5es para concurso p\u00fablico da Sergas s\u00e3o prorrogadas, confira as datas"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A mudan\u00e7a tamb\u00e9m altera a data da prova.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As inscri\u00e7\u00f5es para o concurso p\u00fablico da Serg\u00e1s foram prorrogadas para o dia 2 de agosto. A informa\u00e7\u00e3o foi divulgada pela empresa nesta ter\u00e7a-feira (9).\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mudan\u00e7a tamb\u00e9m altera a data da prova, que agora ser\u00e1 no dia 25 de agosto. As taxas de inscri\u00e7\u00e3o continuam sendo de R$ 115,00 para cargos de n\u00edvel superior e R$ 95,00 para cargos de n\u00edvel m\u00e9dio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As inscri\u00e7\u00f5es tamb\u00e9m s\u00e3o mantidas pela internet. Os candidatos interessados podem obter mais informa\u00e7\u00f5es e acessar o edital completo no\u00a0site da Serg\u00e1s.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">As vagas e benef\u00edcios tamb\u00e9m continuam da forma como foram anunciados com a\u00a0abertura do processo:\u00a0<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para n\u00edvel superior, est\u00e3o dispon\u00edveis as seguintes vagas: 1 para analista organizacional (Administra\u00e7\u00e3o), com sal\u00e1rio de R$ 6.780,85 e jornada de 40 horas semanais; 1 para analista organizacional (Ci\u00eancias Cont\u00e1beis), com sal\u00e1rio de R$ 6.780,85 e jornada de 40 horas semanais; e 2 vagas para engenheiro mec\u00e2nico, com sal\u00e1rio de R$ 10.287,45 e jornada de 40 horas semanais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 para n\u00edvel m\u00e9dio, as vagas disponibilizadas s\u00e3o as seguintes: uma vaga para assistente organizacional, com sal\u00e1rio de R$ 3.794,39 e jornada de 40 horas semanais; uma vaga para t\u00e9cnico em seguran\u00e7a do trabalho; com sal\u00e1rio de R$ 4.743,72 e jornada de 40 horas semanais; e uma vaga para t\u00e9cnico em mec\u00e2nica ou eletromec\u00e2nica, com sal\u00e1rio de R$ 4.743,72 e jornada: 40 horas semanais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: g1 Sergipe <\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A mudan\u00e7a tamb\u00e9m altera a data da prova. As inscri\u00e7\u00f5es para o concurso p\u00fablico da Serg\u00e1s foram prorrogadas para o dia 2 de agosto. A informa\u00e7\u00e3o foi divulgada pela empresa nesta ter\u00e7a-feira (9).\u00a0 A mudan\u00e7a tamb\u00e9m altera a data da prova, que agora ser\u00e1 no dia 25 de agosto. As taxas de inscri\u00e7\u00e3o continuam sendo [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/07\/IMG_2505.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3966"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3966\/revisions"}],"predecessor-version":[{"id":3968,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3966\/revisions\/3968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/3967"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}