{"id":4071,"date":"2024-07-22T10:25:17","date_gmt":"2024-07-22T13:25:17","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4071"},"modified":"2024-07-24T14:34:01","modified_gmt":"2024-07-24T17:34:01","slug":"nao-consigo-confiar-num-cidadao-que-se-esconde-atras-de-discurso-de-fe-pra-fazer-o-que-ele-fez-com-a-gari-de-carmopolis-dispara-lideranca-contra-samuel","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/07\/22\/nao-consigo-confiar-num-cidadao-que-se-esconde-atras-de-discurso-de-fe-pra-fazer-o-que-ele-fez-com-a-gari-de-carmopolis-dispara-lideranca-contra-samuel\/","title":{"rendered":"\u201cN\u00e3o consigo confiar num cidad\u00e3o que se esconde atr\u00e1s de discurso de f\u00e9 pra fazer o que ele fez com a gari de Carm\u00f3polis\u201d, dispara lideran\u00e7a contra Samuel"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A m\u00e1scara do pr\u00e9-candidato a prefeito de Nossa Senhora do Socorro, Samuel Carvalho (Cidadania), caiu h\u00e1 um bom tempo, levando o pastor, que tenta pagar de bom mo\u00e7o para chegar ao poder, sendo um verdadeiro lobo em pele de cordeiro, sofrer intenso desgaste no munic\u00edpio para as elei\u00e7\u00f5es de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mais recente pol\u00eamica envolve den\u00fancias de suposto calote, com Carvalho prometendo pagamentos em troca de apoios para sua campanha eleitoral. Em um v\u00eddeo que circula nas redes sociais, de autoria desconhecida, \u00e9 apontado que ele prometeu pagar a primeira parcela at\u00e9 o \u00faltimo s\u00e1bado, 20, mesma data em que ocorreu sua conven\u00e7\u00e3o. No entanto, ele teria adiado para amanh\u00e3, 23.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma das lideran\u00e7as comentou: \u201cN\u00e3o consigo confiar num cidad\u00e3o que se esconde atr\u00e1s de discurso de f\u00e9 para fazer o que ele fez com a gari de Carm\u00f3polis. N\u00e3o consigo acompanhar uma pessoa dessa.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa lideran\u00e7a, ao criticar Carvalho pela recente pol\u00eamica, tamb\u00e9m relembrou o caso de apropria\u00e7\u00e3o ind\u00e9bita envolvendo o deputado e uma gari, que gerou uma grande repercuss\u00e3o negativa e resultou em uma debandada significativa de apoiadores do grupo de Samuel em Socorro, intensificando o derretimento de sua pr\u00e9-candidatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A informa\u00e7\u00e3o foi publicada pela Revista Realce, que tamb\u00e9m divulgou que a mesma lideran\u00e7a dever\u00e1 declarar apoio ao grupo do prefeito Padre Inaldo (PP), abandonando Samuel.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A m\u00e1scara do pr\u00e9-candidato a prefeito de Nossa Senhora do Socorro, Samuel Carvalho (Cidadania), caiu h\u00e1 um bom tempo, levando o pastor, que tenta pagar de bom mo\u00e7o para chegar ao poder, sendo um verdadeiro lobo em pele de cordeiro, sofrer intenso desgaste no munic\u00edpio para as elei\u00e7\u00f5es de 2024. A mais recente pol\u00eamica envolve [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-4071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/07\/d884acac-f321-47c0-9a63-3bdeda7b0466.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4071"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4071\/revisions"}],"predecessor-version":[{"id":4073,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4071\/revisions\/4073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4072"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}