{"id":4120,"date":"2024-07-29T11:10:08","date_gmt":"2024-07-29T14:10:08","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4120"},"modified":"2024-07-29T11:10:10","modified_gmt":"2024-07-29T14:10:10","slug":"policia-prende-condenado-por-homicidio-motivado-por-divida-de-r-150-em-japaratuba","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/07\/29\/policia-prende-condenado-por-homicidio-motivado-por-divida-de-r-150-em-japaratuba\/","title":{"rendered":"Pol\u00edcia prende condenado por homic\u00eddio motivado por d\u00edvida de R$ 150 em Japaratuba"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um homem de 42 anos investigado por matar outro por n\u00e3o receber o pagamento de tr\u00eas di\u00e1rias como ajudante de pedreiro, no valor de R$ 150, em abril de 2019, foi preso pela Pol\u00edcia Civil na \u00faltima sexta-feira. A informa\u00e7\u00e3o foi divulgada nesta segunda-feira (29).\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Secretaria de Seguran\u00e7a P\u00fablica, no dia 27 de abril, a v\u00edtima teria alegado ao investigado que ainda n\u00e3o tinha recebido o dinheiro da prefeitura para fazer o pagamento, mas que, quando recebesse, repassaria o valor devido. Nesse momento, ele entrou em um bar e o investigado o empurrou.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma hora depois, a v\u00edtima estava pr\u00f3ximo a uma quadra, nas imedia\u00e7\u00f5es, com outros dois colegas. O investigado se aproximou, correndo, e pelas costas e lhe deu um soco na lateral da cabe\u00e7a. A v\u00edtima caiu no ch\u00e3o j\u00e1 desacordada e foi levada para o Hospital de Urg\u00eancia de Sergipe (Huse), onde ficou internada em estado vegetativo por 11 dias, e morreu no dia 7 de maio de 2019.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O homem, que fugiu do munic\u00edpio ap\u00f3s o crime, foi condenado por homic\u00eddio qualificado por motivo f\u00fatil e por recurso que dificulte ou torne imposs\u00edvel a defesa do ofendido. Ele estava foragido desde maio de 2021.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um homem de 42 anos investigado por matar outro por n\u00e3o receber o pagamento de tr\u00eas di\u00e1rias como ajudante de pedreiro, no valor de R$ 150, em abril de 2019, foi preso pela Pol\u00edcia Civil na \u00faltima sexta-feira. A informa\u00e7\u00e3o foi divulgada nesta segunda-feira (29).\u00a0 De acordo com a Secretaria de Seguran\u00e7a P\u00fablica, no dia [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/07\/IMG_8233.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4120"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4120\/revisions"}],"predecessor-version":[{"id":4122,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4120\/revisions\/4122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4121"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}