{"id":4296,"date":"2024-08-26T18:57:06","date_gmt":"2024-08-26T21:57:06","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4296"},"modified":"2024-08-26T18:57:09","modified_gmt":"2024-08-26T21:57:09","slug":"homem-e-preso-suspeito-de-agredir-a-companheira-em-aracaju","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/08\/26\/homem-e-preso-suspeito-de-agredir-a-companheira-em-aracaju\/","title":{"rendered":"Homem \u00e9 preso suspeito de agredir a companheira em Aracaju"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um homem foi preso suspeito de agredir a esposa no bairro Santos Dumont, na zona Norte de Aracaju. O caso ocorreu na tarde deste domingo, 25.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Pol\u00edcia Militar, os policiais foram acionados, atrav\u00e9s do Centro Integrado de Opera\u00e7\u00f5es em Seguran\u00e7a P\u00fablica (Ciosp), para atender uma ocorr\u00eancia de viol\u00eancia contra a mulher. O suspeito foi preso logo ap\u00f3s a equipe do Batalh\u00e3o de Pol\u00edcia de Radiopatrulha (BPRp) chegar ao local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme as informa\u00e7\u00f5es policiais, a v\u00edtima confessou que a conviv\u00eancia com o companheiro estava insustent\u00e1vel diante das brigas do casal. A mulher tamb\u00e9m afirmou que teria sido agredida f\u00edsica e verbalmente, momentos antes da chegada da viatura.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda segundo a PM, os envolvidos foram encaminhados ao Departamento de Atendimento a Grupos Vulner\u00e1veis (DAGV) para ado\u00e7\u00e3o das medidas cab\u00edveis. Os fatos narrados pela v\u00edtima foram confirmados por uma vizinha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um homem foi preso suspeito de agredir a esposa no bairro Santos Dumont, na zona Norte de Aracaju. O caso ocorreu na tarde deste domingo, 25. De acordo com a Pol\u00edcia Militar, os policiais foram acionados, atrav\u00e9s do Centro Integrado de Opera\u00e7\u00f5es em Seguran\u00e7a P\u00fablica (Ciosp), para atender uma ocorr\u00eancia de viol\u00eancia contra a mulher. [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/08\/IMG_3456.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4296"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4296\/revisions"}],"predecessor-version":[{"id":4298,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4296\/revisions\/4298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4297"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}