{"id":4425,"date":"2024-09-11T13:45:28","date_gmt":"2024-09-11T16:45:28","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4425"},"modified":"2024-09-11T13:45:29","modified_gmt":"2024-09-11T16:45:29","slug":"carreta-carregada-com-sal-tomba-na-br-235-deixa-um-ferido-e-provoca-bloqueio-da-via","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/09\/11\/carreta-carregada-com-sal-tomba-na-br-235-deixa-um-ferido-e-provoca-bloqueio-da-via\/","title":{"rendered":"Carreta carregada com sal tomba na BR-235, deixa um ferido e provoca bloqueio da via"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Uma carreta carregada com sal tombou no km 54 da rodovia BR-235, nas proximidades do munic\u00edpio de Itabaiana, na tarde desta ter\u00e7a-feira (10). Uma pessoa ficou ferida e foi conduzida a uma unidade hospitalar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A carreta tombou de forma tranversal \u00e0 pista, provocando o espalhamento de parte das 13 tolenadas de sal que estava sendo transportada. O acidente provocou o bloqueio da via no sentido Aracaju. No sentido contr\u00e1rio, o fluxo precisou ser organizado atrav\u00e9s de Pare\/Siga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agentes da Pol\u00edcia Rodovi\u00e1ria Federal (PRF\/SE) se deslocaram at\u00e9 o local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: A8se<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Uma carreta carregada com sal tombou no km 54 da rodovia BR-235, nas proximidades do munic\u00edpio de Itabaiana, na tarde desta ter\u00e7a-feira (10). Uma pessoa ficou ferida e foi conduzida a uma unidade hospitalar. A carreta tombou de forma tranversal \u00e0 pista, provocando o espalhamento de parte das 13 tolenadas de sal que estava sendo [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":4426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/09\/IMG_9038.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4425"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4425\/revisions"}],"predecessor-version":[{"id":4427,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4425\/revisions\/4427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4426"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}