{"id":4440,"date":"2024-09-12T15:09:44","date_gmt":"2024-09-12T18:09:44","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4440"},"modified":"2024-09-12T18:07:59","modified_gmt":"2024-09-12T21:07:59","slug":"justica-reconhece-que-pesquisa-da-realce-nao-tem-irregularidades-e-reis-entram-em-desespero","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/09\/12\/justica-reconhece-que-pesquisa-da-realce-nao-tem-irregularidades-e-reis-entram-em-desespero\/","title":{"rendered":"Justi\u00e7a reconhece que pesquisa da Realce n\u00e3o tem irregularidades e Reis entram em desespero"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um dos maiores ve\u00edculos do estado e a maior refer\u00eancia pol\u00edtica de Lagarto, conhecida por prever com precis\u00e3o os resultados eleitorais do munic\u00edpio, a Revista Realce vem enfrentando uma s\u00e9rie de ataques orquestrados pela fam\u00edlia Reis nas \u00faltimas semanas, devido a divulga\u00e7\u00e3o de pesquisas que apontam o grupo em desvantagem nas elei\u00e7\u00f5es de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre as investidas, esteve a tentativa de barrar a divulga\u00e7\u00e3o dos levantamentos, sob alega\u00e7\u00e3o de irregularidades. No entanto, a Justi\u00e7a Eleitoral rejeitou essas acusa\u00e7\u00f5es, confirmando a legitimidade e a integridade dos dados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decis\u00e3o caiu como um balde de \u00e1gua fria para o grupo de S\u00e9rgio Reis (PSD), que lida com altos \u00edndices de rejei\u00e7\u00e3o em Lagarto devido a sua imagem de \u201cficha suja\u201d, acumulando v\u00e1rias condena\u00e7\u00f5es por improbidade administrativa, lavagem de dinheiro, peculato e falsidade ideol\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na pesquisa mais recente, publicada nesta quarta-feira, 11, e registrada sob o n\u00famero SE-03784\/2024, S\u00e9rgio amarga a segunda coloca\u00e7\u00e3o, atr\u00e1s de Rafaela Ribeiro (Republicanos), que disparou na lideran\u00e7a e consolidou uma virada hist\u00f3rica nas inten\u00e7\u00f5es de voto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desesperado para evitar que esses n\u00fameros ganhassem notoriedade, S\u00e9rgio tentou, sem sucesso, impedir que os resultados viessem a p\u00fablico \u2014 resultados que indicam um desempenho cada vez mais pr\u00f3ximo ao teto de votos j\u00e1 alcan\u00e7ado pelo Saramandaia na cidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale lembrar que, antes, S\u00e9rgio vangloriava a Realce quando, em dezembro, o mesmo ve\u00edculo o mostrava na lideran\u00e7a da disputa. Agora, por\u00e9m, com a queda nas inten\u00e7\u00f5es de voto, ele e seu grupo passaram a atacar a credibilidade da revista, tentando desacreditar os levantamentos que antes serviam como trunfo para sua campanha.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um dos maiores ve\u00edculos do estado e a maior refer\u00eancia pol\u00edtica de Lagarto, conhecida por prever com precis\u00e3o os resultados eleitorais do munic\u00edpio, a Revista Realce vem enfrentando uma s\u00e9rie de ataques orquestrados pela fam\u00edlia Reis nas \u00faltimas semanas, devido a divulga\u00e7\u00e3o de pesquisas que apontam o grupo em desvantagem nas elei\u00e7\u00f5es de 2024. Entre [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":4443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/09\/3df8c783-2f6d-40f9-ab5c-ea05d20a5620.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4440"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4440\/revisions"}],"predecessor-version":[{"id":4442,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4440\/revisions\/4442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4443"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}