{"id":4450,"date":"2024-09-13T10:34:41","date_gmt":"2024-09-13T13:34:41","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4450"},"modified":"2024-09-13T10:34:42","modified_gmt":"2024-09-13T13:34:42","slug":"pesquisa-mostra-agripino-na-lideranca-da-disputa-pela-prefeitura-de-areia-branca","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/09\/13\/pesquisa-mostra-agripino-na-lideranca-da-disputa-pela-prefeitura-de-areia-branca\/","title":{"rendered":"Pesquisa mostra Agripino na lideran\u00e7a da disputa pela prefeitura de Areia Branca"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Uma pesquisa realizada pelo Instituto Gadu, registrada sob o o n\u00famero SE-07646\/2024, mostrou que, apesar do crescimento de Talysson de Valmir (PL), Agripino segue liderando a disputa eleitoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o levantamento, no cen\u00e1rio espont\u00e2neo, Agripino tem 45,52% das inten\u00e7\u00f5es de voto, seguido por Talysson, que tem 34,08% da prefer\u00eancia do eleitorado. Renato da Eletr\u00f4nica (DC) aparece em terceiro lugar com 1,12%. Indecisos somam 17,71%, enquanto 1,57% afirmam votar em branco ou nulo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No cen\u00e1rio induzido, quando os nomes dos candidatos s\u00e3o apresentados aos entrevistados, Agripino mant\u00e9m a lideran\u00e7a com 47,31%, enquanto Talysson sobe para 35,65%. Renato da Eletr\u00f4nica permanece em terceiro com 2,02%. Os indecisos caem para 12,78%, e os votos brancos e nulos aumentam para 2,24%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesquisa, registrada no Tribunal Superior Eleitoral (TSE) foi realizada nos dias 5 e 6 de setembro com uma amostra de 446 eleitores. A margem de erro \u00e9 de 4,57 pontos percentuais, e o n\u00edvel de confian\u00e7a \u00e9 de 95%.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Uma pesquisa realizada pelo Instituto Gadu, registrada sob o o n\u00famero SE-07646\/2024, mostrou que, apesar do crescimento de Talysson de Valmir (PL), Agripino segue liderando a disputa eleitoral. De acordo com o levantamento, no cen\u00e1rio espont\u00e2neo, Agripino tem 45,52% das inten\u00e7\u00f5es de voto, seguido por Talysson, que tem 34,08% da prefer\u00eancia do eleitorado. Renato da [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":4451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/09\/b47db344-a039-41b4-b154-31e9a2c5fe78.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4450"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4450\/revisions"}],"predecessor-version":[{"id":4452,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4450\/revisions\/4452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4451"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}