{"id":4543,"date":"2024-09-26T16:18:44","date_gmt":"2024-09-26T19:18:44","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4543"},"modified":"2024-09-27T09:19:09","modified_gmt":"2024-09-27T12:19:09","slug":"sergipe-registra-164-ocorrencias-de-colisoes-em-postes-em-2024","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/09\/26\/sergipe-registra-164-ocorrencias-de-colisoes-em-postes-em-2024\/","title":{"rendered":"Sergipe registra 164 ocorr\u00eancias de colis\u00f5es em postes em 2024"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Energisa registrou 164 ocorr\u00eancias envolvendo postes de eletricidade em Sergipe de janeiro a setembro deste ano. Aracaju lidera o ranking das ocorr\u00eancias com registros, principalmente, nos bairros Lamar\u00e3o, Gameleira e Farol\u00e2ndia. Esses acidentes trazem riscos para o condutor do ve\u00edculo e pode impactar o fornecimento de energia na regi\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em Sergipe, as cidades com mais ocorr\u00eancias de colis\u00f5es em postes s\u00e3o: Aracaju, Itabaiana e Nossa Senhora do Socorro. Somente este ano, as ocorr\u00eancias impactaram 215 mil clientes, uma redu\u00e7\u00e3o de 16% quando comparado ao mesmo per\u00edodo do ano passado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O coordenador de Obras da Energisa, Ant\u00f4nio Cleverton, destaca que o investimento em tecnologias, a exemplo de religadores autom\u00e1ticos, postes m\u00f3veis e o uso de equipes de linha viva, que atuam com a rede energizada, contribu\u00edram para que os clientes ficassem menos tempo sem energia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO objetivo \u00e9 que o cliente seja restabelecido o mais r\u00e1pido nessas ocorr\u00eancias. Somente este ano, instalamos 34 religadores autom\u00e1ticos em v\u00e1rios munic\u00edpios. Esses equipamentos isolam o trecho danificado e em at\u00e9 um minuto o fornecimento de energia \u00e9 restabelecido para os clientes. Al\u00e9m disso, temos as equipes de viva que atuam com a rede energizada. A estrutura est\u00e1 sendo substitu\u00edda e o cliente continua com energia el\u00e9trica\u201d, explica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Ant\u00f4nio, em acidentes envolvendo postes de eletricidade a orienta\u00e7\u00e3o \u00e9 que sempre que poss\u00edvel, o condutor evite sair do ve\u00edculo, pois pode haver risco de choque el\u00e9trico, uma vez que podem existir cabos sobre o ve\u00edculo ou pr\u00f3ximos, que podem n\u00e3o ser visualizados pela v\u00edtima. A Energisa deve ser imediatamente acionada para realizar todos os procedimentos com seguran\u00e7a por meio do telefone 0800 079 0196.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Preven\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um sistema de prote\u00e7\u00e3o est\u00e1 sendo implantado pela Energisa desde 2023 para diminuir o impacto das colis\u00f5es em postes. O dispositivo consiste em uma estrutura de concreto com borracha colocada na base do poste. O objetivo \u00e9 diminuir o impacto da colis\u00e3o para o condutor e diminuir os danos nos postes, e consequentemente evitar a falta do fornecimento de energia el\u00e9trica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do risco \u00e0 seguran\u00e7a, outro fator relacionado aos acidentes com postes \u00e9 a responsabilidade de quem ir\u00e1 arcar com os preju\u00edzos. O custo \u00e9 em m\u00e9dia R$ 6 mil que contempla poste, fios e equipamentos danificados e estruturas. Dependendo da complexidade e danos causados, o valor pode ser maior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Infonet<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Energisa registrou 164 ocorr\u00eancias envolvendo postes de eletricidade em Sergipe de janeiro a setembro deste ano. Aracaju lidera o ranking das ocorr\u00eancias com registros, principalmente, nos bairros Lamar\u00e3o, Gameleira e Farol\u00e2ndia. Esses acidentes trazem riscos para o condutor do ve\u00edculo e pode impactar o fornecimento de energia na regi\u00e3o. Em Sergipe, as cidades com [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/09\/IMG_4185.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4543"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4543\/revisions"}],"predecessor-version":[{"id":4545,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4543\/revisions\/4545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4544"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}