{"id":4772,"date":"2024-12-08T17:24:08","date_gmt":"2024-12-08T20:24:08","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4772"},"modified":"2024-12-09T14:49:30","modified_gmt":"2024-12-09T17:49:30","slug":"avenida-pedro-calazans-permanecera-fechada-durante-toda-a-semana","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2024\/12\/08\/avenida-pedro-calazans-permanecera-fechada-durante-toda-a-semana\/","title":{"rendered":"Avenida Pedro Calazans permanecer\u00e1 fechada durante toda a semana"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Os trabalhos continuam nesta segunda-feira, 2, na avenida Pedro Calazans, bairro Get\u00falio Vargas, ap\u00f3s o&nbsp;<strong><a href=\"https:\/\/infonet.com.br\/noticias\/cidade\/tubulacao-da-deso-rompe-e-abre-cratera-avenida-pedro-calazans\/\">rompimento de uma adutora da Companhia de Saneamento de Sergipe (Deso)<\/a><\/strong>ocorrido no domingo, 1\u00ba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O incidente causou a abertura de uma cratera e a entrada de lama, areia e \u00e1gua em im\u00f3veis e estabelecimentos comerciais da localidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O superintendente municipal de Transporte e Tr\u00e2nsito, tenente-coronel Silvio Prado, explica que o trecho entre a rua S\u00e3o Crist\u00f3v\u00e3o e a Mamede Paes Mendon\u00e7a segue totalmente bloqueado, bem como o acesso \u00e0 rua Divina Pastora. \u201cA orienta\u00e7\u00e3o \u00e9 para que os condutores peguem rotas alternativas, como a avenida Gentil Tavares, tanto para o sentido Sul como para o Norte. Desta forma, a popula\u00e7\u00e3o poder\u00e1 chegar ao seu destino final sem passar pela Pedro Calazans. Quem vem da avenida Coelho e Campos e Ayrton Teles s\u00f3 vai conseguir acessar at\u00e9 a Mamede Paes Mendon\u00e7a, ent\u00e3o tamb\u00e9m recomendamos rotas alternativas. Para isso, temos as avenidas paralelas e perpendiculares como a Gentil Tavares, Augusto Franco e a Beira Mar. Estamos com a SMTT no local fazendo esses bloqueios e orientando os condutores a tomarem essas rotas alternativas\u201d, detalha.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Os trabalhos continuam nesta segunda-feira, 2, na avenida Pedro Calazans, bairro Get\u00falio Vargas, ap\u00f3s o&nbsp;rompimento de uma adutora da Companhia de Saneamento de Sergipe (Deso)ocorrido no domingo, 1\u00ba. O incidente causou a abertura de uma cratera e a entrada de lama, areia e \u00e1gua em im\u00f3veis e estabelecimentos comerciais da localidade. O superintendente municipal de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2024\/12\/IMG_0235.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4772"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4772\/revisions"}],"predecessor-version":[{"id":4774,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4772\/revisions\/4774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}