{"id":4825,"date":"2025-01-07T12:36:28","date_gmt":"2025-01-07T15:36:28","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4825"},"modified":"2025-01-07T12:36:29","modified_gmt":"2025-01-07T15:36:29","slug":"barra-anuncia-suspensao-temporaria-de-servicos-por-causa-de-dividas","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/01\/07\/barra-anuncia-suspensao-temporaria-de-servicos-por-causa-de-dividas\/","title":{"rendered":"Barra anuncia suspens\u00e3o tempor\u00e1ria de servi\u00e7os por causa de d\u00edvidas"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">O servi\u00e7os p\u00fablicos da Superintend\u00eancia Municipal de Transportes e Tr\u00e2nsito (SMTT), Guarda Civil Municipal e Salva-vidas foram interrompidos temporariamente no munic\u00edpio da Barra dos Coqueiros. A informa\u00e7\u00e3o foi divulgada pelas redes sociais nesta segunda-feira, 6.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Prefeitura da Barra dos Coqueiros, a interrup\u00e7\u00e3o dos servi\u00e7os decorre da falta de combust\u00edvel, diante de d\u00edvidas deixadas pela administra\u00e7\u00e3o passada. Al\u00e9m disso, foram identificados problemas em instala\u00e7\u00f5es da gest\u00e3o, como salas em condi\u00e7\u00f5es prec\u00e1rias, computadores n\u00e3o localizados e carros sucateados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEm virtude do cen\u00e1rio de caos em que foram encontradas algumas instala\u00e7\u00f5es da Prefeitura de Barra dos Coqueiros, informamos que alguns servi\u00e7os p\u00fablicos encontram-se em fase de reestrutura\u00e7\u00e3o\u201d, explicou a gest\u00e3o municipal em nota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">fonte: G1 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>O servi\u00e7os p\u00fablicos da Superintend\u00eancia Municipal de Transportes e Tr\u00e2nsito (SMTT), Guarda Civil Municipal e Salva-vidas foram interrompidos temporariamente no munic\u00edpio da Barra dos Coqueiros. A informa\u00e7\u00e3o foi divulgada pelas redes sociais nesta segunda-feira, 6. De acordo com a Prefeitura da Barra dos Coqueiros, a interrup\u00e7\u00e3o dos servi\u00e7os decorre da falta de combust\u00edvel, diante de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/01\/IMG_1849.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4825"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4825\/revisions"}],"predecessor-version":[{"id":4827,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4825\/revisions\/4827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4826"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}