{"id":4837,"date":"2025-01-25T11:55:29","date_gmt":"2025-01-25T14:55:29","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=4837"},"modified":"2025-01-26T11:57:02","modified_gmt":"2025-01-26T14:57:02","slug":"condutor-fica-ferido-apos-carro-bater-em-poste-no-bairro-13-de-julho","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/01\/25\/condutor-fica-ferido-apos-carro-bater-em-poste-no-bairro-13-de-julho\/","title":{"rendered":"Condutor fica ferido ap\u00f3s carro bater em poste no bairro 13 de Julho"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um acidente de tr\u00e2nsito foi registrado na noite desta sexta-feira 24, por volta das 18h50, na Av. Governador Paulo Barreto de Menezes, no Bairro 13 de Julho, em Aracaju.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O sinistro, do tipo choque, envolveu um autom\u00f3vel que colidiu contra um poste de ilumina\u00e7\u00e3o no canteiro central da via, deixando uma v\u00edtima ferida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com relatos, o condutor foi fechado por outro ve\u00edculo ao fazer uma curva, perdendo o controle e colidindo com o poste. Com o impacto, o poste caiu no lado oposto ao deslocamento do ve\u00edculo, mas n\u00e3o atingiu outros autom\u00f3veis que transitavam na via no momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um acidente de tr\u00e2nsito foi registrado na noite desta sexta-feira 24, por volta das 18h50, na Av. Governador Paulo Barreto de Menezes, no Bairro 13 de Julho, em Aracaju. O sinistro, do tipo choque, envolveu um autom\u00f3vel que colidiu contra um poste de ilumina\u00e7\u00e3o no canteiro central da via, deixando uma v\u00edtima ferida. De acordo [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":4838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/01\/IMG_2693.png","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4837"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4837\/revisions"}],"predecessor-version":[{"id":4839,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4837\/revisions\/4839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/4838"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}