{"id":540,"date":"2020-08-17T10:35:06","date_gmt":"2020-08-17T13:35:06","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=540"},"modified":"2020-08-17T10:35:09","modified_gmt":"2020-08-17T13:35:09","slug":"em-visita-a-aracaju-empresario-luciano-hang-fala-sobre-possibilidade-da-instalacao-de-uma-loja-havan-em-itabaiana","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/08\/17\/em-visita-a-aracaju-empresario-luciano-hang-fala-sobre-possibilidade-da-instalacao-de-uma-loja-havan-em-itabaiana\/","title":{"rendered":"Em visita a Aracaju, empres\u00e1rio Luciano Hang fala sobre possibilidade da instala\u00e7\u00e3o de uma loja Havan em Itabaiana"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Ser\u00e1 que Itabaiana poder\u00e1 ser sede de uma loja da Havan?! Essa possibilidade foi comentada na manh\u00e3 de hoje, 07, pelo empres\u00e1rio fundador da rede, Luciano Hang, que est\u00e1 em Aracaju, onde ser\u00e1 instalada a primeira loja de Sergipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele bateu um papo com o jovem empres\u00e1rio itabaianense Bruno Tuch\u00ea, que \u00e9 f\u00e3 de Luciano e j\u00e1 o encontrou em algumas ocasi\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLogo logo eu quero visitar Itabaiana, que o &#8216;Tuch\u00ea&#8217; fala que \u00e9 um polo. \u00c9 nesse tipo de cidades que a Havan gosta de estar\u201d, enfatizou Luciano Hang.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>HAVAN:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Havan \u00e9 uma rede de grandes lojas de departamento do Brasil, com uma infinidade de produtos, como cama, mesa e banho, brinquedos, eletrodom\u00e9sticos, etc. A primeira loja em Sergipe ser\u00e1 constru\u00edda na Av. Tancredo Neves, na capital. O pontap\u00e9 para in\u00edcio da obra foi dado hoje, com a visita de Luciano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fundada em 1986, a Havan \u00e9 conhecida pelas suas lojas com fachadas similares \u00e0 da Casa Branca e pelas r\u00e9plicas da Est\u00e1tua da Liberdade instaladas na frente da maioria das suas filiais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 que Itabaiana poder\u00e1 ser sede de uma loja da Havan?! Essa possibilidade foi comentada na manh\u00e3 de hoje, 07, pelo empres\u00e1rio fundador da rede, Luciano Hang, que est\u00e1 em Aracaju, onde ser\u00e1 instalada a primeira loja de Sergipe. Ele bateu um papo com o jovem empres\u00e1rio itabaianense Bruno Tuch\u00ea, que \u00e9 f\u00e3 de Luciano [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[34,2],"tags":[],"class_list":["post-540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresarial","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/08\/1-LUCIANO-HANG-HAVAN-2020-1.JPG.jpg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=540"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/540\/revisions"}],"predecessor-version":[{"id":542,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/540\/revisions\/542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/541"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}