{"id":572,"date":"2020-08-17T11:56:12","date_gmt":"2020-08-17T14:56:12","guid":{"rendered":"http:\/\/sergipeinforma.com\/?p=572"},"modified":"2020-08-17T11:56:28","modified_gmt":"2020-08-17T14:56:28","slug":"quem-marcou-o-gol-da-fake-news-em-lagarto-sobre-a-votacao-para-prorrogar-o-auxilio","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2020\/08\/17\/quem-marcou-o-gol-da-fake-news-em-lagarto-sobre-a-votacao-para-prorrogar-o-auxilio\/","title":{"rendered":"Quem marcou o gol da fake news em Lagarto sobre a vota\u00e7\u00e3o para prorrogar o aux\u00edlio?"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Depois da vota\u00e7\u00e3o acerca do prolongamento do aux\u00edlio emergencial at\u00e9 dezembro, que ocorreu na semana passada no Plen\u00e1rio da C\u00e2mara dos Deputados, veio ao debate p\u00fablico a cr\u00edtica, por grande parte da popula\u00e7\u00e3o, aos parlamentares que votaram em desfavor da proposta que previa continuidade das parcelas de R$ 600,00 reais para os brasileiros at\u00e9 dezembro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A representa\u00e7\u00e3o lagartense ampliou o placar na vota\u00e7\u00e3o desfavor\u00e1vel: os deputados federais Gustinho Ribeiro e F\u00e1bio Reis, o popular Fabinho, meteram os p\u00e9s pelas m\u00e3os na decis\u00e3o sobre a amplia\u00e7\u00e3o do per\u00edodo do aux\u00edlio do Governo Federal at\u00e9 o fim deste ano, mat\u00e9ria proposta atrav\u00e9s de uma emenda lan\u00e7ada pelo PT. Mas apenas um deles, quis limpar a lamban\u00e7a que foi essa atitude em rela\u00e7\u00e3o \u00e0 influ\u00eancia com o eleitorado. E o fez de forma meio atabalhoada, embora se p\u00f4de verificar uma tentativa gaiata de esperteza no discurso\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/opapajaca.com\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-24-at-11.37.42-1024x767.jpeg\" alt=\"\" class=\"wp-image-10837\"\/><figcaption>Gustinho e Fabinho seriam, respectivamente, o 04 e 05 do Centr\u00e3o a servi\u00e7o do Capit\u00e3o no Plen\u00e1rio da C\u00e2mara?<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Primeiro, o atacante foi para cima da rede social. F\u00e1bio acusou de fake news, os compartilhamentos no Whatsapp \u2013 que possui o mando de campo das fakes \u2013 de que ele tinha se manifestado contra o aux\u00edlio. Mas uma r\u00e1pida jogada no google e&nbsp;<em>p\u00eanalti!&nbsp;<\/em>l\u00e1 est\u00e1 o voto contr\u00e1rio \u00e0 prorroga\u00e7\u00e3o do aux\u00edlio no site da C\u00e2mara. Coisa paradoxal; a falta do ca\u00e7ula dos Reis Pol\u00edticos foi ter usado a internet para executar o lance \u2013 na r\u00e1dio at\u00e9 que ele poderia ter invadido a \u00e1rea -, mas contra um oponente que tem as caracter\u00edsticas da r\u00e1pida acessibilidade e ampla disponibilidade de informa\u00e7\u00e3o n\u00e3o teve jogo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois ele avan\u00e7ou para a oposi\u00e7\u00e3o, jogando a bola da fake news contra o careca (n\u00e3o o da Sele\u00e7\u00e3o Brasileira de 86 e \u00eddolo do Napoli), o careca Nininho da Bolo Bom, que tamb\u00e9m disse que Fabinho foi do contra; o rapaz do Bolo contra-atacou contando com a ajuda do VAR (\u00e1rbitro de v\u00eddeo), e foi l\u00e1 o boleiro, leu peda\u00e7o de emenda e mostrou os n\u00e3os de F\u00e1bio e Gustinho \u00e0 proposta de prorrogar o aux\u00edlio. S\u00f3 faltou fazer embaixadinha.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De olho no lance, o fato \u00e9 que o deputado Saramandaia subestimou o advers\u00e1rio e a intelig\u00eancia de boa parte dos lagartenses; talvez ele nem fosse totalmente opositor da extens\u00e3o do dinheiro emergencial, mas entrou de salto alto em campo ao manejar o movimento errado s\u00f3 para n\u00e3o dar o gostinho do gol merit\u00f3rio ser marcado pelo Partido dos Trabalhadores \u2013 que recentemente foi rebaixado para a segundona e tenta subir -, criador da propositura. Foi a cl\u00e1ssica defesa com a m\u00e3o do jogador de linha, quando a bola j\u00e1 tem endere\u00e7o certo \u2013 cart\u00e3o vermelho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>No \u00faltimo escanteio antes do apito final, aos 48 do segundo tempo, F\u00e1bio apelou para a for\u00e7a da camisa, dizendo que foi duas vezes a favor do aux\u00edlio, e depois foi para a \u00e1rea, prometendo que n\u00e3o seria jamais um empecilho \u00e0 ajuda financeira do Governo. Segundo ele, o que diziam era uma \u201cmaldade\u201d, uma verdadeira falta de&nbsp;<em>fair play&nbsp;<\/em>(falta de esp\u00edrito esportivo dos opositores), mas como o tiro de canto estava sendo batido pela m\u00eddia independente e contou com o futebol\u00edstico oportunismo da oposi\u00e7\u00e3o, F\u00e1bio Reis deu uma cabe\u00e7ada forte para evitar a derrota, mas certeira na dire\u00e7\u00e3o do pr\u00f3prio gol, marcando contra, fazendo o gola\u00e7o da est\u00f3ria da fake news. J\u00e1 Gustinho, n\u00e3o quis revanche.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Depois da vota\u00e7\u00e3o acerca do prolongamento do aux\u00edlio emergencial at\u00e9 dezembro, que ocorreu na semana passada no Plen\u00e1rio da C\u00e2mara dos Deputados, veio ao debate p\u00fablico a cr\u00edtica, por grande parte da popula\u00e7\u00e3o, aos parlamentares que votaram em desfavor da proposta que previa continuidade das parcelas de R$ 600,00 reais para os brasileiros at\u00e9 dezembro. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2019-04-24-at-17.57.49-1-e1595603967221-1140x640-1.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=572"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/572\/revisions"}],"predecessor-version":[{"id":574,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/572\/revisions\/574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/573"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}