{"id":5818,"date":"2025-07-02T13:34:16","date_gmt":"2025-07-02T16:34:16","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=5818"},"modified":"2025-07-02T13:34:18","modified_gmt":"2025-07-02T16:34:18","slug":"acumulado-de-chuvas-do-mes-de-junho-em-sergipe-e-superior-a-media-esperada","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/07\/02\/acumulado-de-chuvas-do-mes-de-junho-em-sergipe-e-superior-a-media-esperada\/","title":{"rendered":"Acumulado de chuvas do m\u00eas de junho em Sergipe \u00e9 superior \u00e0 m\u00e9dia esperada"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">De acordo com a Ger\u00eancia de Meteorologia da Secretaria de Estado do Meio Ambiente, Sustentabilidade e A\u00e7\u00f5es Clim\u00e1ticas (Semac), o balan\u00e7o de chuvas de junho foi acima da m\u00e9dia em todo o territ\u00f3rio de Sergipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o \u00f3rg\u00e3o, a previs\u00e3o deve permanecer pelo m\u00eas de julho em Sergipe e nos demais estados do Nordeste. Por\u00e9m, na regi\u00e3o do semi\u00e1rido, as precipita\u00e7\u00f5es ser\u00e3o compat\u00edveis com a m\u00e9dia registrada no per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como exemplo, o acumulado de chuvas chegou a ser superior a 500 mil\u00edmetros em Pacatuba, munic\u00edpio do baixo S\u00e3o Francisco, onde o normal para junho \u00e9 140 mm, e superior a 400 mm em outros tr\u00eas munic\u00edpios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foi o caso de Ilha das Flores, tamb\u00e9m na regi\u00e3o do baixo S\u00e3o Francisco, onde choveu 486,1 mm, quando o normal para o per\u00edodo \u00e9 145 mm.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isto se deve ao prolongamento da baixa press\u00e3o e umidade atmosf\u00e9ricas e do aquecimento do Oceano Atl\u00e2ntico adjacente, o que provoca grande possibilidade de chuvas no estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: A8se<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>De acordo com a Ger\u00eancia de Meteorologia da Secretaria de Estado do Meio Ambiente, Sustentabilidade e A\u00e7\u00f5es Clim\u00e1ticas (Semac), o balan\u00e7o de chuvas de junho foi acima da m\u00e9dia em todo o territ\u00f3rio de Sergipe. Segundo o \u00f3rg\u00e3o, a previs\u00e3o deve permanecer pelo m\u00eas de julho em Sergipe e nos demais estados do Nordeste. Por\u00e9m, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/07\/IMG_3641.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5818"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5818\/revisions"}],"predecessor-version":[{"id":5820,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5818\/revisions\/5820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/5819"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}