{"id":5822,"date":"2025-07-02T13:36:25","date_gmt":"2025-07-02T16:36:25","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=5822"},"modified":"2025-07-02T13:36:27","modified_gmt":"2025-07-02T16:36:27","slug":"caminhoneiro-e-encontrado-morto-em-posto-de-combustiveis-em-malhada-dos-bois","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/07\/02\/caminhoneiro-e-encontrado-morto-em-posto-de-combustiveis-em-malhada-dos-bois\/","title":{"rendered":"Caminhoneiro \u00e9 encontrado morto em posto de combust\u00edveis em Malhada dos Bois"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Um caminhoneiro foi encontrado morto em um posto de combust\u00edveis, no Povoado Cruz das Donzelas, em\u00a0Malhada dos Bois, nesta ter\u00e7a-feira (1\u00ba). A informa\u00e7\u00e3o foi confirmada pela Pol\u00edcia Rodovi\u00e1ria Federal (PRF).\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a PRF, funcion\u00e1rios do posto encontraram o homem morto dentro da cabine do caminh\u00e3o. O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) foi acionado e constatou a morte no local.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Instituto M\u00e9dico Legal (IML) recolheu o corpo e n\u00e3o identificou nenhuma marca de viol\u00eancia. A causa da morte ser\u00e1 investigada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: G1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Um caminhoneiro foi encontrado morto em um posto de combust\u00edveis, no Povoado Cruz das Donzelas, em\u00a0Malhada dos Bois, nesta ter\u00e7a-feira (1\u00ba). A informa\u00e7\u00e3o foi confirmada pela Pol\u00edcia Rodovi\u00e1ria Federal (PRF).\u00a0 De acordo com a PRF, funcion\u00e1rios do posto encontraram o homem morto dentro da cabine do caminh\u00e3o. O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/07\/IMG_3642.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5822"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5822\/revisions"}],"predecessor-version":[{"id":5824,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5822\/revisions\/5824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}