{"id":5853,"date":"2025-07-08T11:35:33","date_gmt":"2025-07-08T14:35:33","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=5853"},"modified":"2025-07-08T11:35:34","modified_gmt":"2025-07-08T14:35:34","slug":"homem-e-preso-por-porte-ilegal-de-arma-e-embriaguez-ao-volante-em-itabaiana","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/07\/08\/homem-e-preso-por-porte-ilegal-de-arma-e-embriaguez-ao-volante-em-itabaiana\/","title":{"rendered":"Homem \u00e9 preso por porte ilegal de arma e embriaguez ao volante em Itabaiana"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">Policiais do Regimento de Cavalaria Mecanizada de Motopatrulhamento (Getam), do 3\u00ba Batalh\u00e3o da Pol\u00edcia Militar, prenderam em flagrante um homem por porte ilegal de arma de fogo e suspeita de embriaguez ao volante no munic\u00edpio de Itabaiana. A a\u00e7\u00e3o aconteceu na tarde do \u00faltimo domingo, 6, na comunidade S\u00edtio Porto, zona rural do munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a PM, a equipe recebeu uma den\u00fancia an\u00f4nima informando que um homem estaria em atitude suspeita dentro de um ve\u00edculo. Ao chegarem ao local indicado, os policiais localizaram o carro e tentaram realizar a abordagem, mas o condutor tentou fugir. A tentativa de evas\u00e3o foi frustrada e ele foi interceptado pouco depois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a revista no interior do autom\u00f3vel, os agentes encontraram uma pistola calibre .380 com um carregador contendo quatro muni\u00e7\u00f5es \u2014 tr\u00eas intactas e uma deflagrada. O suspeito afirmou possuir a documenta\u00e7\u00e3o de posse da arma, mas n\u00e3o apresentou autoriza\u00e7\u00e3o para o porte, que \u00e9 obrigat\u00f3rio para o transporte fora da resid\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, os policiais constataram que o homem apresentava sinais vis\u00edveis de embriaguez. A suspeita foi confirmada ap\u00f3s procedimentos na delegacia, para onde ele foi levado juntamente com o armamento apreendido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O caso foi registrado e encaminhado para os procedimentos legais cab\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: Itnet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>Policiais do Regimento de Cavalaria Mecanizada de Motopatrulhamento (Getam), do 3\u00ba Batalh\u00e3o da Pol\u00edcia Militar, prenderam em flagrante um homem por porte ilegal de arma de fogo e suspeita de embriaguez ao volante no munic\u00edpio de Itabaiana. A a\u00e7\u00e3o aconteceu na tarde do \u00faltimo domingo, 6, na comunidade S\u00edtio Porto, zona rural do munic\u00edpio. Segundo [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/07\/IMG_3723.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5853"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5853\/revisions"}],"predecessor-version":[{"id":5855,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5853\/revisions\/5855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/5854"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}