{"id":5872,"date":"2025-07-11T15:08:27","date_gmt":"2025-07-11T18:08:27","guid":{"rendered":"https:\/\/sergipeinforma.com.br\/?p=5872"},"modified":"2025-07-11T15:08:29","modified_gmt":"2025-07-11T18:08:29","slug":"secretaria-de-saude-de-aracaju-alerta-populacao-sobre-alisantes-de-cabelo","status":"publish","type":"post","link":"https:\/\/sergipeinforma.com.br\/index.php\/2025\/07\/11\/secretaria-de-saude-de-aracaju-alerta-populacao-sobre-alisantes-de-cabelo\/","title":{"rendered":"Secretaria de Sa\u00fade de Aracaju alerta popula\u00e7\u00e3o sobre alisantes de cabelo"},"content":{"rendered":"<span class=\"cb-itemprop\" itemprop=\"reviewBody\">\n<p class=\"wp-block-paragraph\">A Secretaria Municipal da Sa\u00fade (SMS) de Aracaju emitiu um alerta sobre o uso de produtos para alisamento de cabelo que contenham formol (formalde\u00eddo) ou \u00e1cido gliox\u00edlico, ressaltando que alisantes desse tipo n\u00e3o s\u00f3 s\u00e3o proibidos, como tamb\u00e9m podem causar graves riscos \u00e0 sa\u00fade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As consequ\u00eancias do uso de produtos capilares com subst\u00e2ncias irregulares v\u00e3o desde irrita\u00e7\u00f5es na pele, queimaduras no couro cabeludo, queda dos fios, alergias, problemas respirat\u00f3rios e tamb\u00e9m na vis\u00e3o. Vale destacar que as implica\u00e7\u00f5es podem acometer tanto quem aplica o alisante quanto quem recebe o procedimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As \u00fanicas subst\u00e2ncias autorizadas pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) s\u00e3o: \u00e1cido tioglic\u00f3lico e seus sais, \u00e9steres do \u00e1cido tioglic\u00f3lico, hidr\u00f3xido de s\u00f3dio, pot\u00e1ssio, l\u00edtio ou c\u00e1lcio (associado \u00e0 guanidina); sulfitos e bissulfitos inorg\u00e2nicos, pirogalol e \u00e1cido tiol\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dessa forma, o uso do formol s\u00f3 \u00e9 permitido como conservante, quando a concentra\u00e7\u00e3o \u00e9 mais baixa (at\u00e9 0,2%), ou como endurecedor de unhas (at\u00e9 5%). A adi\u00e7\u00e3o da subst\u00e2ncia a produtos prontos \u00e9 considerada infra\u00e7\u00e3o sanit\u00e1ria e crime hediondo, de acordo com o artigo 273 do C\u00f3digo Penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para descobrir se o produto \u00e9 autorizado pela Anvisa, \u00e9 poss\u00edvel realizar a busca no\u00a0<strong>sistema de consulta de alisantes registrados.<\/strong>\u00a0\u00c9 necess\u00e1rio ter em m\u00e3os o n\u00famero do processo (que come\u00e7a com 25351), o nome do produto ou o CNPJ da empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: A8se<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal da Sa\u00fade (SMS) de Aracaju emitiu um alerta sobre o uso de produtos para alisamento de cabelo que contenham formol (formalde\u00eddo) ou \u00e1cido gliox\u00edlico, ressaltando que alisantes desse tipo n\u00e3o s\u00f3 s\u00e3o proibidos, como tamb\u00e9m podem causar graves riscos \u00e0 sa\u00fade. As consequ\u00eancias do uso de produtos capilares com subst\u00e2ncias irregulares v\u00e3o [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sergipeinforma.com.br\/wp-content\/uploads\/2025\/07\/IMG_3773.jpeg","_links":{"self":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5872"}],"version-history":[{"count":1,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5872\/revisions"}],"predecessor-version":[{"id":5874,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5872\/revisions\/5874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media\/5873"}],"wp:attachment":[{"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergipeinforma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}